{"id":10,"date":"2024-08-28T06:26:50","date_gmt":"2024-08-28T06:26:50","guid":{"rendered":"https:\/\/ancientcitybangkok.com\/?page_id=10"},"modified":"2025-05-05T01:24:04","modified_gmt":"2025-05-04T19:54:04","slug":"heim","status":"publish","type":"page","link":"https:\/\/ancientcitybangkok.com\/de","title":{"rendered":"Heim"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"10\" class=\"elementor elementor-10\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-461ccd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"461ccd5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db0c83d\" data-id=\"db0c83d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9fb55e1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fb55e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1d79202\" data-id=\"1d79202\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-711dbc9 elementor-widget elementor-widget-heading\" data-id=\"711dbc9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Delfinshow Phuket - Dolphins Bay Phuket Tickets<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95a7915 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"95a7915\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf4f211 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"bf4f211\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.7<\/strong><\/span> (4.3K Bewertungen)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2192deb elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"2192deb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTriplyn Holidays ist eine vertrauensw\u00fcrdige Marke, die kuratierte Erlebnisse anbietet, mit denen Sie die Dolphin Show Phuket erkunden k\u00f6nnen. Buchen Sie vertrauensvoll und genie\u00dfen Sie ein nahtloses Abenteuer, das f\u00fcr ein unvergessliches Erlebnis bei einer der Topattraktionen Thailands konzipiert wurde.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0d2e73 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"a0d2e73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTriplyn Holidays bietet eine unvergessliche Delfinshow in Phuket. Buchen Sie bei uns f\u00fcr ein nahtloses Abenteuer!\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3939b57 elementor-hidden-mobile\" data-id=\"3939b57\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d9c111 elementor-widget elementor-widget-image\" data-id=\"1d9c111\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"680\" height=\"453\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.avif\" class=\"attachment-large size-large wp-image-2752\" alt=\"Delfinshow Phuket\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.avif 680w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-400x266.avif 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-600x400.avif 600w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-24d4d6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24d4d6f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-045eb13\" data-id=\"045eb13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08760cc elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"08760cc\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiMDg3NjBjYyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiIwODc2MGNjIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6IjA4NzYwY2MifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiIwODc2MGNjIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiMDg3NjBjYyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiIwODc2MGNjIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiIwODc2MGNjIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiMDg3NjBjYyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6IjA4NzYwY2MifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6IjA4NzYwY2MifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6IjA4NzYwY2MifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiIwODc2MGNjIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"08760cc\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiMDg3NjBjYyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d68a43e\" data-id=\"d68a43e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f42f93 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1f42f93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c27f017 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"c27f017\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-417e71a elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"417e71a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.3<\/strong><\/span> (4,7 KB)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d964353 elementor-widget elementor-widget-heading\" data-id=\"d964353\" data-element_type=\"widget\" id=\"title1\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\">Normale Sitzplatzkarte (Ausl\u00e4nder)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cda2c7 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"4cda2c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Preiswerte Sitzpl\u00e4tze in den Reihen E, F und G<\/strong>: Genie\u00dfen Sie die unglaubliche Delfin- und Robbenshow mit bequemen und preisg\u00fcnstigen Sitzpl\u00e4tzen im Stammbereich.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Interaktive Delfin- und Robbenshow<\/strong>: Erleben Sie spektakul\u00e4re Darbietungen von Delfinen und Robben zu drei verschiedenen Showzeiten (11:00, 14:00 und 17:00 Uhr), perfekt f\u00fcr alle Altersgruppen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Aktivit\u00e4ten nach der Show<\/strong>: Nehmen Sie an aufregenden Aktivit\u00e4ten teil, darunter Fotogelegenheiten mit Delfinen und Robben und sogar Schwimmen mit Delfinen gegen Aufpreis.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Ideal f\u00fcr Familien<\/strong>: Kinderfreundliche Richtlinien mit kostenlosem Eintritt f\u00fcr Kinder unter 90 cm (kein Sitzplatz vorhanden) und erm\u00e4\u00dfigten Preisen f\u00fcr Kinder zwischen 90 und 130 cm.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Vorabbuchung erforderlich<\/strong>: Sichern Sie sich Ihre Tickets mindestens einen Tag vor der Show, um die Verf\u00fcgbarkeit sicherzustellen und Entt\u00e4uschungen zu vermeiden.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Keine Stornierungs- oder R\u00fcckerstattungsbedingungen<\/strong>: Buchungen sind endg\u00fcltig, planen Sie also entsprechend.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11225f7 elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"11225f7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3ODQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4c25ab9\" data-id=\"4c25ab9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc78179 elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dc78179\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab Normaler Sitzplatz (Reihe E, F, G)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbde88e elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"bbde88e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3ODQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caa199f elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"caa199f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>600.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdfc2a7 elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"bdfc2a7\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46f087c elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"46f087c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regularer-sitzplatz-ticket-auslander\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85c791f elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"85c791f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc0NSIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0363408 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0363408\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab Normaler Sitzplatz (Reihe E, F, G)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-d205cbd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d205cbd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-60e4b77\" data-id=\"60e4b77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2a9e1e elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"a2a9e1e\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiYTJhOWUxZSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImEyYTllMWUifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJhMmE5ZTFlIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJhMmE5ZTFlIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJhMmE5ZTFlIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiYTJhOWUxZSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImEyYTllMWUifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6ImEyYTllMWUifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJhMmE5ZTFlIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6ImEyYTllMWUifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiJhMmE5ZTFlIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiYTJhOWUxZSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2a9e1e\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiYTJhOWUxZSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f410857\" data-id=\"f410857\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58e2890 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"58e2890\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca5b38c elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"ca5b38c\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1eb8aa elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"c1eb8aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.2<\/strong><\/span> (4,1K)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c976f elementor-widget elementor-widget-heading\" data-id=\"74c976f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\">Deluxe-Sitzplatzticket (Ausl\u00e4nder)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fb34e7 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"8fb34e7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Prime Deluxe-Sitzpl\u00e4tze in den Reihen C und D<\/strong>: Erleben Sie die Show mit hervorragender Sicht auf die Delfin- und Robbenvorf\u00fchrungen in einem bequemen Sitzbereich.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Delfin- und Robbenshow<\/strong>: Genie\u00dfen Sie unglaubliche Darbietungen von Delfinen und Robben mit interaktiven Tricks und Stunts zu drei verf\u00fcgbaren Showzeiten (11:00, 14:00 und 17:00 Uhr).<\/span><\/li><li><span style=\"color: #000000;\"><strong>Aktivit\u00e4ten nach der Show<\/strong>: Nehmen Sie an Aktivit\u00e4ten wie Fotogelegenheiten mit Delfinen und Robben teil und genie\u00dfen Sie zus\u00e4tzliche Erlebnisse wie das Schwimmen mit Delfinen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>G\u00fcnstige Lage<\/strong>: Die Show findet im Dolphins Bay Phuket statt, 33\/50, Chalong, Mueang Phuket District, leicht erreichbar \u00fcber <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Google Maps<\/a>.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Kinderfreundliche Politik<\/strong>: Kinder unter 90 cm haben ohne Sitzplatz freien Eintritt, w\u00e4hrend f\u00fcr Kinder zwischen 90 und 130 cm ein Kinderpreis gilt.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Voranmeldung erforderlich<\/strong>: Sichern Sie sich Ihren Sitzplatz durch eine Buchung mindestens 1 Tag im Voraus, Stornierungen sind nicht m\u00f6glich.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-579376f elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"579376f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MTYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-38b680d\" data-id=\"38b680d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c28487 elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8c28487\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab Deluxe-Sitz (Reihe C, D)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81eaeca elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"81eaeca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MTYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53126d8 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"53126d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>800.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e32a83b elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"e32a83b\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd2768d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"dd2768d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-foreigners\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fef0378 elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"fef0378\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc1NiIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f5bf69 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6f5bf69\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab Deluxe-Sitz (Reihe C, D)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-60175af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60175af\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5c161ec\" data-id=\"5c161ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8febd3 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"c8febd3\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJjOGZlYmQzIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImM4ZmViZDMifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJjOGZlYmQzIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJjOGZlYmQzIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJjOGZlYmQzIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiYzhmZWJkMyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImM4ZmViZDMifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6ImM4ZmViZDMifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6ImM4ZmViZDMifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiYzhmZWJkMyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiJjOGZlYmQzIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiYzhmZWJkMyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8febd3\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiYzhmZWJkMyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d2a89cd\" data-id=\"d2a89cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14e0e44 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"14e0e44\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8c596d elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"a8c596d\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-329dd31 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"329dd31\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.4<\/strong><\/span> (4,5 KB)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aded786 elementor-widget elementor-widget-heading\" data-id=\"aded786\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\">VIP-Sitzplatzticket (Ausl\u00e4nder)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d543bc9 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"d543bc9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>VIP-Sitzpl\u00e4tze in Reihe B<\/strong>: Genie\u00dfen Sie erstklassige Sitzpl\u00e4tze mit hervorragender Sicht auf die Delfin- und Robbenshow f\u00fcr ein intensives Erlebnis.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Delfin- und Robbenvorf\u00fchrungen<\/strong>: Erleben Sie zu bestimmten Spielzeiten (11:00, 14:00 und 17:00 Uhr) spannende Vorstellungen mit Zaubertricks und Interaktionen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Interaktive Aktivit\u00e4ten<\/strong>: Nehmen Sie an Aktivit\u00e4ten nach der Show teil, beispielsweise am Magic Touch, an Fotomotiven mit Delfinen und Robben und am Schwimmen mit Delfinen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Kinderfreundliche Richtlinien<\/strong>: Kinder unter 90 cm haben freien Eintritt ohne Sitzplatz und f\u00fcr das Schwimmen mit Delfinen gelten besondere Richtlinien.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Erstklassige Lage in Phuket<\/strong>: G\u00fcnstig gelegen bei 33\/50, Chalong, Mueang Phuket District, leicht erreichbar \u00fcber <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Google Maps Standort<\/a>.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Buchen Sie im Voraus<\/strong>: Sichern Sie sich Ihr VIP-Erlebnis, indem Sie mindestens 1 Tag im Voraus buchen. Stornierungen oder R\u00fcckerstattungen sind nicht m\u00f6glich.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f725970 elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"f725970\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3ODciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-79fb641\" data-id=\"79fb641\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f57494a elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f57494a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c VIP-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab VIP-Sitz (Reihe B)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b720f4 elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"7b720f4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3ODciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cacdba elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"3cacdba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>875.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4a3d35 elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"a4a3d35\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfee064 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"bfee064\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitz-ticket-auslander\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65d7f4f elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"65d7f4f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc2MyIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc44e20 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dc44e20\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c VIP-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab VIP-Sitz (Reihe B)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-de3864f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de3864f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f0e4ceb\" data-id=\"f0e4ceb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6694f66 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"6694f66\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiI2Njk0ZjY2In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiNjY5NGY2NiJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6IjY2OTRmNjYifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiI2Njk0ZjY2In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiI2Njk0ZjY2In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6IjY2OTRmNjYifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6IjY2OTRmNjYifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6IjY2OTRmNjYifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiI2Njk0ZjY2In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiNjY5NGY2NiJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiI2Njk0ZjY2In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiNjY5NGY2NiJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6694f66\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiNjY5NGY2NiJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fa1a327\" data-id=\"fa1a327\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-661f255 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"661f255\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd4ade8 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"dd4ade8\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59a9abc elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"59a9abc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.2<\/strong><\/span> (4,4 KB)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b4004 elementor-widget elementor-widget-heading\" data-id=\"a0b4004\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\">VVIP-Sitzplatzticket (Ausl\u00e4nder)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ee0e72 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"6ee0e72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Exklusive VVIP-Sitzpl\u00e4tze<\/strong>: Genie\u00dfen Sie die beste Sicht auf die Delfin- und Robbenshow mit den VVIP-Sitzen in Reihe A, die ein unvergleichliches Erlebnis bieten.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Delfin- und Robbenvorf\u00fchrungen<\/strong>: Erleben Sie die unglaublichen Darbietungen von Delfinen und Robben, einschlie\u00dflich aufregender Tricks und Interaktionen, zu festgelegten Showzeiten (11:00, 14:00, 17:00 Uhr).<\/span><\/li><li><span style=\"color: #000000;\"><strong>Interaktive Erlebnisse<\/strong>: Nehmen Sie nach der Show an Aktivit\u00e4ten wie Magic Touch, Fotom\u00f6glichkeiten mit Delfinen und Robben und mehr teil.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Praktische Showzeiten<\/strong>: T\u00e4glich au\u00dfer montags ge\u00f6ffnet, mit drei Spielzeiten zur Auswahl. Die Tore \u00f6ffnen 15 Minuten vor jeder Show.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Erstklassige Lage<\/strong>: Das Hotel liegt im Herzen von Phuket bei 33\/50, Chalong, Mueang Phuket District, leicht erreichbar mit <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Google Maps Standort<\/a>.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Kinderfreundliches Erlebnis<\/strong>: Kinder unter 90 cm haben freien Eintritt (ohne Sitzplatz), was den Ausflug f\u00fcr die ganze Familie ideal macht.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bab64e elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"7bab64e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3OTIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-df5ae48\" data-id=\"df5ae48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0636472 elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0636472\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Exklusiver VVIP-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab VVIP-Sitz (Reihe A)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53ec4af elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"53ec4af\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3OTIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5586565 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"5586565\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>1,050.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c74ae1 elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"7c74ae1\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-595744e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"595744e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-sitzplatz-ticket-auslander\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ecdfa3 elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"3ecdfa3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc3MCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c730dd4 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c730dd4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Exklusiver VVIP-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab VVIP-Sitz (Reihe A)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-fa1312a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa1312a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-17bd1cf\" data-id=\"17bd1cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d406b21 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"d406b21\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6ImQ0MDZiMjEifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJkNDA2YjIxIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJkNDA2YjIxIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJkNDA2YjIxIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImQ0MDZiMjEifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJkNDA2YjIxIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiZDQwNmIyMSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImQ0MDZiMjEifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiZDQwNmIyMSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6ImQ0MDZiMjEifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiZDQwNmIyMSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiJkNDA2YjIxIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d406b21\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiZDQwNmIyMSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-15437b2\" data-id=\"15437b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a28d33 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1a28d33\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac50514 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"ac50514\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbbfba1 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"bbbfba1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.6<\/strong><\/span> (4,9 KB)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6d5eb6 elementor-widget elementor-widget-heading\" data-id=\"a6d5eb6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\">Swimming With Dolphin Ticket (Foreigners)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf9cf34 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"bf9cf34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Delfin-Interaktionserlebnis<\/strong>: Schwimmen Sie mit Delfinen in einer sicheren und unterhaltsamen Umgebung und genie\u00dfen Sie die enge und pers\u00f6nliche Interaktion mit diesen intelligenten Lebewesen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>T\u00e4gliche Showzeiten<\/strong>: Drei Spielzeiten verf\u00fcgbar: 11:00 Uhr, 14:00 Uhr und 17:00 Uhr, t\u00e4glich au\u00dfer montags.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Spannende Delfin- und Robbenshows<\/strong>: Schauen Sie sich vor Ihrem Schwimmerlebnis die Robben- und Delfinvorf\u00fchrungen an, um Ihren Besuch noch unterhaltsamer zu gestalten.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Kinderfreundliche Politik<\/strong>: Am Schwimmen k\u00f6nnen Kinder ab 6 Jahren teilnehmen, j\u00fcngere Kinder k\u00f6nnen unter Aufsicht ihrer Eltern teilnehmen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>G\u00fcnstige Lage<\/strong>: Befindet sich in 33\/50, Chalong, Bezirk Mueang Phuket, Phuket, <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Google Maps Standort<\/a>.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Voranmeldung erforderlich<\/strong>: Buchen Sie Ihre Tickets mindestens einen Tag im Voraus, um Ihr Delfinschwimmerlebnis zu sichern.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-760d481 elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"760d481\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3OTUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a1f5b2b\" data-id=\"a1f5b2b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2684162 elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2684162\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zum Schwimmen mit Delfinen und zur Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc76 F\u00fcr Kinder ab 6 Jahren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa0d74d elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"fa0d74d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3OTUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a82f65 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"4a82f65\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>5,600.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe9ca78 elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"fe9ca78\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ff6dd5 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1ff6dd5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-foreigners\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79c0893 elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"79c0893\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4NSIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf5bfb5 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cf5bfb5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zum Schwimmen mit Delfinen und zur Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc76 F\u00fcr Kinder ab 6 Jahren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e02ea3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e02ea3e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-58759c7\" data-id=\"58759c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8ede94 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"a8ede94\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6ImE4ZWRlOTQifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImE4ZWRlOTQifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImE4ZWRlOTQifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiYThlZGU5NCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJhOGVkZTk0In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiYThlZGU5NCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiYThlZGU5NCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJhOGVkZTk0In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6ImE4ZWRlOTQifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJhOGVkZTk0In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJhOGVkZTk0In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiJhOGVkZTk0In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a8ede94\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiYThlZGU5NCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2097029\" data-id=\"2097029\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6741aae elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6741aae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6d6d70 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"c6d6d70\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a69ddb elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"7a69ddb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.3<\/strong><\/span> (4,7 KB)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-941e7e5 elementor-widget elementor-widget-heading\" data-id=\"941e7e5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\">Normale Sitzplatzkarte (Einwohner Thailands)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78abff2 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"78abff2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Exklusive Delfinshow<\/strong> mit regul\u00e4ren Sitzpl\u00e4tzen f\u00fcr thail\u00e4ndische Einwohner und hervorragender Sicht in den Reihen E, F und G.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Mehrere Spielzeiten<\/strong> um 11:00 Uhr, 14:00 Uhr und 17:00 Uhr, sodass den Besuchern flexible M\u00f6glichkeiten zur Nutzung des Erlebnisses geboten werden.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Interaktive Robbenshow<\/strong> gefolgt von einer aufregenden Delfinshow mit lustigen Aktivit\u00e4ten, einschlie\u00dflich Schwimmen und Fotom\u00f6glichkeiten mit Delfinen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Familienfreundliche Attraktion<\/strong> Es gilt eine Kinderregelung, die Kindern unter 90 cm Gr\u00f6\u00dfe freien Eintritt bietet und keinen Sitzplatz zur Verf\u00fcgung stellt.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Buchungsbedingungen<\/strong>: Um Ihren Sitzplatz zu sichern und Entt\u00e4uschungen zu vermeiden, m\u00fcssen Sie Ihre Tickets mindestens 1 Tag im Voraus buchen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Stornierungsbedingungen<\/strong>: Sobald die Buchung best\u00e4tigt ist, sind keine R\u00fcckerstattungen oder Stornierungen mehr m\u00f6glich. Planen Sie Ihren Besuch daher sorgf\u00e4ltig.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f2547a elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"3f2547a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3OTgiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7a3ab87\" data-id=\"7a3ab87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4153e44 elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4153e44\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab Normaler Sitzplatz (Reihe E, F, G)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262bfc9 elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"262bfc9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3OTgiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9687a86 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"9687a86\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>335.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58b3709 elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"58b3709\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ded79e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3ded79e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-regulare-sitzplatzkarte-fur-thai-einwohner\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13bc46e elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"13bc46e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc0NSIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-017f525 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"017f525\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab Normaler Sitzplatz (Reihe E, F, G)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1d9be48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d9be48\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7092a00\" data-id=\"7092a00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b60b59c elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"b60b59c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJiNjBiNTljIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJiNjBiNTljIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiYjYwYjU5YyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImI2MGI1OWMifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJiNjBiNTljIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiYjYwYjU5YyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiYjYwYjU5YyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImI2MGI1OWMifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6ImI2MGI1OWMifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJiNjBiNTljIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6ImI2MGI1OWMifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiJiNjBiNTljIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b60b59c\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiYjYwYjU5YyJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f3f5b38\" data-id=\"f3f5b38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36270f0 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"36270f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a0f4b7 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"7a0f4b7\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12a7b2b elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"12a7b2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.2<\/strong><\/span> (4,1K)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2b1a8 elementor-widget elementor-widget-heading\" data-id=\"2e2b1a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\">Deluxe-Sitzplatzticket (Einwohner Thailands)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe39cd8 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"fe39cd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Deluxe-Sitzerlebnis<\/strong>: Positioniert in den Reihen C und D f\u00fcr eine optimale Sicht auf die Delfin- und Robbenvorf\u00fchrungen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Interaktive Robben- und Delfinshow<\/strong>: Genie\u00dfen Sie eine 15-min\u00fctige Robbenshow, gefolgt von einer aufregenden Delfinshow, Schwimmeinheiten und mehr.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Mehrere Spielzeiten<\/strong>: Verf\u00fcgbar um 11:00 Uhr, 14:00 Uhr und 17:00 Uhr, sodass Sie die beste Zeit f\u00fcr Ihren Besuch flexibel w\u00e4hlen k\u00f6nnen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Familienfreundlich<\/strong>: Kinder unter 90 cm haben freien Eintritt (kein Sitzplatz vorhanden), w\u00e4hrend f\u00fcr Kinder zwischen 90 und 130 cm ein Kinderpreis gilt.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Einfache Buchungs- und Stornierungsbedingungen<\/strong>: Buchen Sie mindestens einen Tag im Voraus, da alle Buchungen endg\u00fcltig sind und keine R\u00fcckerstattungen oder Stornierungen m\u00f6glich sind.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Bequemer Standort<\/strong>: Befindet sich in 33\/50, Chalong, Mueang Phuket District, Thailand, leicht erreichbar \u00fcber Google Maps <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Link<\/a>.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-336b65c elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"336b65c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MDEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a6c4bad\" data-id=\"a6c4bad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-124d22d elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"124d22d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Deluxe-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab Deluxe-Sitz (Reihe C, D)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-443ecf7 elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"443ecf7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MDEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ba7f1 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"12ba7f1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>425.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b38f48f elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"b38f48f\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de2634f elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"de2634f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-deluxe-seat-ticket-thai-residents\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f20cf93 elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"f20cf93\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc1NiIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-662bde9 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"662bde9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Deluxe-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab Deluxe-Sitz (Reihe C, D)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5e9a79a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e9a79a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ae4c8fc\" data-id=\"ae4c8fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c3bd50 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"6c3bd50\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiI2YzNiZDUwIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiI2YzNiZDUwIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiNmMzYmQ1MCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiI2YzNiZDUwIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6IjZjM2JkNTAifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiNmMzYmQ1MCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiI2YzNiZDUwIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiI2YzNiZDUwIn0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiNmMzYmQ1MCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6IjZjM2JkNTAifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6IjZjM2JkNTAifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6IjZjM2JkNTAifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6c3bd50\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiNmMzYmQ1MCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b50635d\" data-id=\"b50635d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7255de6 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7255de6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-876d6c8 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"876d6c8\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b54d1a8 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"b54d1a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.4<\/strong><\/span> (4,5 KB)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97aff54 elementor-widget elementor-widget-heading\" data-id=\"97aff54\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\">VIP-Sitzplatzticket (Einwohner Thailands)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85306f4 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"85306f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Erstklassige Sitzpl\u00e4tze in Reihe B<\/strong>: Genie\u00dfen Sie ein hautnahes und intensives Erlebnis mit VIP-Sitzpl\u00e4tzen in Reihe B f\u00fcr eine optimale Sicht auf die Delfin- und Robbenshows.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Spannende Robben- und Delfinshow<\/strong>: Sehen Sie sich eine 15-min\u00fctige Robbenshow an, gefolgt von einer actiongeladenen Delfinvorf\u00fchrung mit Aktivit\u00e4ten wie Schwimmen und Fotom\u00f6glichkeiten.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Mehrere Spielzeiten verf\u00fcgbar<\/strong>: Die Shows finden t\u00e4glich um 11:00 Uhr, 14:00 Uhr und 17:00 Uhr statt, sodass Sie die Zeit flexibel w\u00e4hlen k\u00f6nnen, die Ihnen am besten gef\u00e4llt.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Kinderfreundliche Politik<\/strong>: Kinder unter 90 cm haben freien Eintritt (kein Sitzplatz vorhanden), w\u00e4hrend f\u00fcr Kinder zwischen 90 und 130 cm der Kinderpreis gilt.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Richtlinien f\u00fcr einfache Buchung<\/strong>: Buchen Sie Ihre Tickets mindestens einen Tag im Voraus, vor 18:00 Uhr, um sich Ihren Platz f\u00fcr die Show am n\u00e4chsten Tag zu sichern.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Bequemer Standort<\/strong>: Der Veranstaltungsort ist leicht erreichbar unter 33\/50, Chalong, Mueang Phuket District, Phuket, mit einem <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Google Maps-Link<\/a>.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7994fa elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"c7994fa\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MDYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e9d4455\" data-id=\"e9d4455\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2052724 elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2052724\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c VIP-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab VIP-Sitz (Reihe B)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b56759b elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"b56759b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MDYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84ca63f elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"84ca63f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>515.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15ede6b elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"15ede6b\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-045ea32 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"045ea32\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vip-sitzticket-fur-thailandische-einwohner\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-826d452 elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"826d452\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc2MyIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81b4e60 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"81b4e60\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c VIP-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab VIP-Sitz (Reihe B)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-77e06c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77e06c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c7cadbe\" data-id=\"c7cadbe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dade9e8 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"dade9e8\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6ImRhZGU5ZTgifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6ImRhZGU5ZTgifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJkYWRlOWU4In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiZGFkZTllOCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImRhZGU5ZTgifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJkYWRlOWU4In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiZGFkZTllOCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiJkYWRlOWU4In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiJkYWRlOWU4In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiZGFkZTllOCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6ImRhZGU5ZTgifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiJkYWRlOWU4In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"dade9e8\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiZGFkZTllOCJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a68274d\" data-id=\"a68274d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3498e33 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3498e33\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-205b336 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"205b336\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298b7a7 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"298b7a7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.2<\/strong><\/span> (4,4 KB)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bafd06 elementor-widget elementor-widget-heading\" data-id=\"3bafd06\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\">VVIP-Sitzplatzticket (Einwohner Thailands)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23c9a46 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"23c9a46\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Premium-VVIP-Sitzpl\u00e4tze in Reihe A<\/strong>: Genie\u00dfen Sie die beste Sicht mit exklusiven Sitzpl\u00e4tzen in der ersten Reihe f\u00fcr das ultimative Delfin- und Robbenshow-Erlebnis.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Spannende Robben- und Delfinshows<\/strong>: Genie\u00dfen Sie eine actionreiche Robbenshow, gefolgt von einer spektakul\u00e4ren Delfinvorf\u00fchrung, perfekt f\u00fcr alle Altersgruppen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Flexible Spielzeiten<\/strong>: W\u00e4hlen Sie f\u00fcr einen passenden Besuch zwischen den Vorstellungszeiten 11:00 Uhr, 14:00 Uhr und 17:00 Uhr.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Kinderfreundlicher Eintritt<\/strong>: Kinder unter 90 cm haben freien Eintritt (kein Sitzplatz vorhanden); f\u00fcr Kinder zwischen 90 und 130 cm gilt ein Kinderpreis.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Buchen Sie im Voraus<\/strong>: Sichern Sie sich Ihren Platz, indem Sie mindestens einen Tag im Voraus buchen, mit einer praktischen Buchungsrichtlinie.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Leicht erreichbarer Standort<\/strong>: Finden Sie den Veranstaltungsort ganz einfach unter 33\/50, Chalong, Mueang Phuket District, Phuket, mit detaillierten <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Google Maps-Standort<\/a>.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a195d97 elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"a195d97\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MDkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c186648\" data-id=\"c186648\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9963692 elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9963692\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Exklusiver VVIP-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab VVIP-Sitz (Reihe A)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d726df1 elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"d726df1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MDkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee3bc78 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"ee3bc78\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>600.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90c92b0 elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"90c92b0\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39beea8 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"39beea8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-vvip-seat-ticket-thai-residents\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b6e544 elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"8b6e544\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc3MCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cab625 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7cab625\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Exklusiver VVIP-Zugang zur Delfin- und Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83c\udfab VVIP-Sitz (Reihe A)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-065f0f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"065f0f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1d1af01\" data-id=\"1d1af01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ec88e5 elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"8ec88e5\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiOGVjODhlNSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiI4ZWM4OGU1In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphins Bay Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LnBuZyIsInNsaWRlc2hvdyI6IjhlYzg4ZTUifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphin Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLUJheS1QaHVrZXQucG5nIiwic2xpZGVzaG93IjoiOGVjODhlNSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Bay-Phuket.png\" alt=\"Dolphin Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphin Show Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiI4ZWM4OGU1In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.png\" alt=\"Delfinshow Phuket Ticketpreis\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphin Show Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NiwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6IjhlYzg4ZTUifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.png\" alt=\"Delfinshow Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphin Show Phuket Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGluLVNob3ctUGh1a2V0LVRpY2tldHMucG5nIiwic2xpZGVzaG93IjoiOGVjODhlNSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Tickets.png\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3NywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC1QcmljZS5wbmciLCJzbGlkZXNob3ciOiI4ZWM4OGU1In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.png\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphins Bay Phuket Ticket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3OCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LVRpY2tldC5wbmciLCJzbGlkZXNob3ciOiI4ZWM4OGU1In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket.png\" alt=\"Eintrittskarte f\u00fcr Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphins Bay Phuket\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktUGh1a2V0LnBuZyIsInNsaWRlc2hvdyI6IjhlYzg4ZTUifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket.png\" alt=\"Dolphins Bay Phuket\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphins Bay Ticket Price\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MSwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0LVByaWNlLnBuZyIsInNsaWRlc2hvdyI6IjhlYzg4ZTUifQ%3D%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Ticket-Price.png\" alt=\"Eintrittspreis f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphins Bay Tickets\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4MywidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXktVGlja2V0cy5wbmciLCJzbGlkZXNob3ciOiI4ZWM4OGU1In0%3D\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Tickets.png\" alt=\"Eintrittskarten f\u00fcr Dolphins Bay\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8ec88e5\" data-elementor-lightbox-title=\"Dolphins Bay\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg4NCwidXJsIjoiaHR0cHM6XC9cL2FuY2llbnRjaXR5YmFuZ2tvay5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEwXC9Eb2xwaGlucy1CYXkucG5nIiwic2xpZGVzaG93IjoiOGVjODhlNSJ9\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay.png\" alt=\"Delfinbucht\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9c1f820\" data-id=\"9c1f820\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85bfc73 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"85bfc73\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dolphins Bay Phuket<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f81b68 elementor-widget__width-auto elementor-widget elementor-widget-rating\" data-id=\"5f81b68\" data-element_type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"1\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"1\" role=\"img\" aria-label=\"Bewertet mit 1 von 1\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-star\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M450 75L338 312 88 350C46 354 25 417 58 450L238 633 196 896C188 942 238 975 275 954L500 837 725 954C767 975 813 942 804 896L763 633 942 450C975 417 954 358 913 350L663 312 550 75C529 33 471 33 450 75Z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a506ecf elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"a506ecf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #f0ad4e;\"><strong>4.6<\/strong><\/span> (4,9 KB)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-209573b elementor-widget elementor-widget-heading\" data-id=\"209573b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\">Swimming With Dolphin Ticket (Thai Residents)<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d07f5f elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"7d07f5f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Exklusive Delfin-Interaktion<\/strong>: Erleben Sie das Schwimmen mit Delfinen hautnah in einer sicheren und interaktiven Umgebung.<\/span><\/li><li><span style=\"color: #000000;\"><strong>T\u00e4glich ge\u00f6ffnet<\/strong>: Genie\u00dfen Sie die Show und die Schwimmeinheiten t\u00e4glich au\u00dfer montags mit drei Showzeiten um 11:00, 14:00 und 17:00 Uhr.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Familienfreundliche Aktivit\u00e4t<\/strong>: Geeignet f\u00fcr Erwachsene und Kinder (ab 6 Jahren), mit besonderen Bestimmungen f\u00fcr j\u00fcngere Kinder unter elterlicher Aufsicht.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Spannende Delfin- und Robbenshows<\/strong>: Sehen Sie sich aufregende Robben- und Delfinshows an, bevor Sie in die Delfinschwimm-Session eintauchen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>G\u00fcnstige Lage<\/strong>: Leicht erreichbar bei 33\/50, Chalong, Mueang Phuket District, Phuket, mit <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Google Maps Standort<\/a> bereitgestellt.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Vorreservierung erforderlich<\/strong>: Buchen Sie Ihr Schwimmerlebnis mindestens 1 Tag im Voraus, um sich Ihren Platz f\u00fcr dieses unglaubliche Erlebnis zu sichern.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-431c0e3 elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"431c0e3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MTIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ff1d9f8\" data-id=\"ff1d9f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a27b935 elementor-align-left elementor-icon-list--layout-inline elementor-mobile-align-left elementor-hidden-desktop elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a27b935\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zum Schwimmen mit Delfinen und zur Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc76 F\u00fcr Kinder ab 6 Jahren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-670e55c elementor-mobile-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"670e55c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4MTIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leistungen &amp; wichtige Infos anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-692d836 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"692d836\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#3647;<\/span>5,600.00<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92ddee8 elementor-widget__width-auto kjgojE elementor-widget elementor-widget-html\" data-id=\"92ddee8\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"styles__DiscountTagContainer-sc-ooevs-1 kjgojE\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"20\" fill=\"none\"><path fill=\"#0097b3\" d=\"M5.806 1.706A4 4 0 0 1 9.083 0H10v20h-.917a4 4 0 0 1-3.277-1.706l-4.2-6a4 4 0 0 1 0-4.588l4.2-6Z\"><\/path><\/svg><div class=\"styles__DiscountTextContainer-sc-ooevs-0 hbOuWy\"><p class=\"discount-text\">Erwachsene<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dac45c4 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"dac45c4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ancientcitybangkok.com\/de\/tickets\/dolphins-bay-phuket-swimming-with-dolphin-ticket-thai-residents\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-273d1ad elementor-align-justify elementor-hidden-desktop elementor-hidden-tablet elementor-mobile-align-justify elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"273d1ad\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4NSIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Details<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f6413 elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"64f6413\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u26a1 Sofortige Best\u00e4tigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udcf1 Handyticket<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u23f3 Flexible Dauer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc2c Zugang zum Schwimmen mit Delfinen und zur Robbenshow<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udc76 F\u00fcr Kinder ab 6 Jahren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\ud83d\udeab Keine Transfers inbegriffen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7eaff43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eaff43\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c4a6d33\" data-id=\"c4a6d33\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9eb0224 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9eb0224\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cfde252\" data-id=\"cfde252\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b063f3c elementor-widget elementor-widget-heading\" data-id=\"b063f3c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Erleben Sie die Magie der Delfinshow in Phuket \u2013 Ihr ultimatives Meeresabenteuer<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-097bf4e elementor-widget elementor-widget-text-editor\" data-id=\"097bf4e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><a href=\"https:\/\/ancientcitybangkok.com\/de\">Delfinshow Phuket<\/a> in Dolphins Bay bietet Besuchern jeden Alters ein fesselndes Erlebnis und zeigt die bemerkenswerten Talente von Delfinen und Robben in einer Reihe unterhaltsamer Darbietungen. Dieses Meeresspektakel ist t\u00e4glich au\u00dfer montags ge\u00f6ffnet und beginnt um 11:00 Uhr, 14:00 Uhr und 17:00 Uhr. Es kombiniert atemberaubende Stunts, synchronisierte Routinen und interaktive Erlebnisse, darunter Schwimmen mit Delfinen. Der Veranstaltungsort befindet sich in g\u00fcnstiger Lage in 33\/50 Chalong, Bezirk Mueang Phuket, Thailand, und bietet eine Vielzahl von Sitzm\u00f6glichkeiten, darunter regul\u00e4re, Deluxe-, VIP- und VVIP-Sitze. Mit mobilen Ticketoptionen, sofortiger Best\u00e4tigung und Zugang zu einem flexiblen Zeitplan sorgt Dolphins Bay f\u00fcr ein nahtloses und unvergessliches Erlebnis.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-343be59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"343be59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d791538\" data-id=\"d791538\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4175b94 elementor-widget elementor-widget-heading\" data-id=\"4175b94\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Planen Sie Ihren Besuch der Delfinshow Phuket \u2013 Dolphins Bay<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac72e47 elementor-widget elementor-widget-text-editor\" data-id=\"ac72e47\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Machen Sie das Beste aus Ihrem Besuch, indem Sie alle interaktiven und aufregenden Erlebnisse erkunden, die Sie im Dolphins Bay Phuket erwarten.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-d32bea7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d32bea7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2a126ca\" data-id=\"2a126ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ae23b2 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"6ae23b2\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1121\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1121\" aria-expanded=\"false\">Wichtige Informationen<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1122\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1122\" aria-expanded=\"false\">Highlights<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1123\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1123\" aria-expanded=\"false\">Einschl\u00fcsse<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1124\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1124\" aria-expanded=\"false\">Aktivit\u00e4ten<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1125\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1125\" aria-expanded=\"false\">Sendungen<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1126\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1126\" aria-expanded=\"false\">Regeln<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1127\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1127\" aria-expanded=\"false\">Ausstattung und Zugang<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1128\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1128\" aria-expanded=\"false\">Tipps<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1129\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1129\" aria-expanded=\"false\">Speisem\u00f6glichkeiten<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1121\" aria-expanded=\"false\">Wichtige Informationen<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1121\" tabindex=\"0\" hidden=\"false\"><h3><span style=\"color: #000000;\"><img decoding=\"async\" class=\"alignleft wp-image-2865\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Maps.png\" alt=\"Dolphins Bay Phuket Karten\" width=\"318\" height=\"450\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Maps.png 1587w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Maps-768x1086.png 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Maps-1086x1536.png 1086w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Maps-1448x2048.png 1448w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Maps-400x566.png 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Maps-600x849.png 600w\" sizes=\"(max-width: 318px) 100vw, 318px\" \/>Wichtige Informationen<\/span><\/h3><p><strong>Adresse:<\/strong> 33\/50, Chalong, Bezirk Mueang Phuket, Phuket 83130, Thailand<br \/><strong>Tage der offenen T\u00fcr:<\/strong> Jeden Tag au\u00dfer Montag<br \/><strong>Vorstellungszeiten:<\/strong> 11:00 Uhr, 14:00 Uhr und 17:00 Uhr<br \/><strong>Google Maps Standort:<\/strong> <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Hier finden Sie uns<\/a><\/span><\/p><h3>\u00d6ffentliche Verkehrsmittel<\/h3><p>Anreise <a href=\"https:\/\/ancientcitybangkok.com\/de\">Dolphins Bay Phuket<\/a> ist mit verschiedenen \u00f6ffentlichen Verkehrsmitteln ganz einfach:<\/p><ul><li><strong>Lokale Taxis und Grab:<\/strong> Taxis und Mitfahrdienste wie Grab sind praktisch f\u00fcr Reisen von Ort zu Ort.<\/li><li><strong>Songthaew (Lokalbus):<\/strong> Sie k\u00f6nnen an gr\u00f6\u00dferen Orten in Phuket, wie Patong oder Kata Beach, in ein Songthaew steigen \u2013 eine preiswerte und unterhaltsame Art, sich fortzubewegen.<\/li><li><strong>Motorradvermietung:<\/strong> Wenn Sie Flexibilit\u00e4t bevorzugen, ist das Mieten eines Motorrads eine beliebte und kosteng\u00fcnstige M\u00f6glichkeit, Phuket zu erkunden und zur Delfinshow zu gelangen.<\/li><\/ul><h3>Beste Reisezeit<\/h3><p>Die Delfinshow in Dolphins Bay Phuket findet das ganze Jahr \u00fcber statt, au\u00dfer montags. Die beste Zeit f\u00fcr einen Besuch ist unter der Woche, wenn weniger los ist und Sie die Show bequemer genie\u00dfen k\u00f6nnen. Die Morgenshows um 11:00 Uhr sind ideal f\u00fcr k\u00fchleres Wetter, w\u00e4hrend die Zeitfenster um 14:00 Uhr und 17:00 Uhr die Flexibilit\u00e4t bieten, vor oder nach der Show andere Attraktionen in der N\u00e4he von Phuket zu erkunden.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1122\" aria-expanded=\"false\">Highlights<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1122\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1122\" tabindex=\"0\" hidden=\"hidden\"><h3><span style=\"color: #000000;\"><img decoding=\"async\" class=\"alignleft wp-image-2860\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.jpg\" alt=\"Ticketpreis f\u00fcr Dolphins Bay Phuket\" width=\"296\" height=\"197\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price.jpg 2048w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price-1536x1025.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Ticket-Price-600x400.jpg 600w\" sizes=\"(max-width: 296px) 100vw, 296px\" \/>Highlights<\/span><\/h3><ul><li><span style=\"color: #000000;\"><strong>Atemberaubende Delfin- und Robbenvorf\u00fchrungen:<\/strong> Erleben Sie die synchronisierte Akrobatik und die verspielten M\u00e4tzchen von Delfinen und Robben in einer 40-min\u00fctigen Show.<\/span><\/li><li><span style=\"color: #000000;\"><strong>VVIP-, VIP-, Deluxe- und regul\u00e4re Sitzpl\u00e4tze:<\/strong> W\u00e4hlen Sie aus verschiedenen Sitzm\u00f6glichkeiten, um Ihr Erlebnis mit der besten Aussicht zu verbessern.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Interaktive Sitzungen:<\/strong> M\u00f6glichkeiten zur engen Interaktion wie \u201eSchwimmen mit Delfinen\u201c und Fototermine.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Familienfreundlicher Spa\u00df:<\/strong> Perfekt f\u00fcr Besucher jeden Alters und bietet Unterhaltung und Bildung f\u00fcr Kinder und Erwachsene gleicherma\u00dfen.<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1123\" aria-expanded=\"false\">Einschl\u00fcsse<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1123\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1123\" tabindex=\"0\" hidden=\"hidden\"><h3><span style=\"color: #000000;\">Einschl\u00fcsse \/ Ausschl\u00fcsse<\/span><\/h3><h4><span style=\"color: #000000;\"><strong>Einschl\u00fcsse:<\/strong><\/span><\/h4><ul><li><span style=\"color: #000000;\">Zugang zu den Delfin- und Robbenshows<\/span><\/li><li><span style=\"color: #000000;\">Auswahl der Sitzkategorie (VVIP, VIP, Deluxe oder Regular)<\/span><\/li><li><span style=\"color: #000000;\">Fotom\u00f6glichkeiten mit Delfinen und Robben (ggf. fallen zus\u00e4tzliche Geb\u00fchren an)<\/span><\/li><li><span style=\"color: #000000;\">Optionales Schwimmen mit Delfinen (erfordert separates Ticket)<\/span><\/li><\/ul><h4><span style=\"color: #000000;\"><strong>Ausschl\u00fcsse:<\/strong><\/span><\/h4><ul><li><span style=\"color: #000000;\">Transfers zum und vom Veranstaltungsort<\/span><\/li><li><span style=\"color: #000000;\">Mahlzeiten und Snacks w\u00e4hrend der Show<\/span><\/li><li><span style=\"color: #000000;\">Pers\u00f6nliche Ausgaben wie Souvenirs und zus\u00e4tzliche Fotos<\/span><\/li><li><span style=\"color: #000000;\">Schwimmen mit Delfinen, sofern nicht anders im Ticket angegeben<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1124\" aria-expanded=\"false\">Aktivit\u00e4ten<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1124\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1124\" tabindex=\"0\" hidden=\"hidden\"><h3><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2846\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-scaled.jpg\" alt=\"Delphin-Show-Preis\" width=\"296\" height=\"197\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-scaled.jpg 2560w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-1536x1025.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-2048x1367.jpg 2048w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-600x400.jpg 600w\" sizes=\"(max-width: 296px) 100vw, 296px\" \/>Aktivit\u00e4ten<\/span><\/h3><ul><li><span style=\"color: #000000;\"><strong>Delfin- und Robbenshow:<\/strong> Genie\u00dfen Sie eine spektakul\u00e4re 40-min\u00fctige Vorstellung mit Delfinen und Robben.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Schwimmen mit Delfinen:<\/strong> Eine einmalige Chance, mit diesen intelligenten Lebewesen zu schwimmen (Voranmeldung erforderlich).<\/span><\/li><li><span style=\"color: #000000;\"><strong>Fotom\u00f6glichkeiten:<\/strong> Halten Sie Erinnerungen fest, indem Sie mit Delfinen und Robben posieren.<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1125\" aria-expanded=\"false\">Sendungen<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1125\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1125\" tabindex=\"0\" hidden=\"hidden\"><h3><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2840\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Phuket.jpg\" alt=\"Dolphin Phuket\" width=\"246\" height=\"164\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Phuket.jpg 1566w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Phuket-768x513.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Phuket-1536x1026.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Phuket-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Phuket-600x401.jpg 600w\" sizes=\"(max-width: 246px) 100vw, 246px\" \/>Sendungen<\/span><\/h3><ul><li><span style=\"color: #000000;\"><strong>Robbenschau:<\/strong> Jede Vorstellung beginnt mit einer 15-min\u00fctigen Robbenshow, bei der die Tiere ihre spielerischen M\u00e4tzchen und Tricks vorf\u00fchren.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Delfinshow:<\/strong> Die Haupt-Delfinshow dauert 25 Minuten und umfasst erstaunliche Stunts, Spr\u00fcnge und synchronisierte Tricks, die von trainierten Delfinen vorgef\u00fchrt werden.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Schwimmen &amp; Interaktion:<\/strong> Nach jeder Show k\u00f6nnen Besucher, die das Schwimmerlebnis im Voraus gebucht haben, in einer kontrollierten und beaufsichtigten Umgebung mit den Delfinen interagieren.<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1126\" aria-expanded=\"false\">Regeln<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1126\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1126\" tabindex=\"0\" hidden=\"hidden\"><h3><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2850\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.jpg\" alt=\"Delfinshow Phuket\" width=\"296\" height=\"198\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.jpg 1616w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-768x513.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-1536x1027.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-600x401.jpg 600w\" sizes=\"(max-width: 296px) 100vw, 296px\" \/>Regeln<\/span><\/h3><ol><li><span style=\"color: #000000;\"><strong>Sitzpl\u00e4tze &amp; Showeinlass:<\/strong> Bitte nehmen Sie Ihren Platz entsprechend der Ticketkategorie und der zugewiesenen Sitzplatznummer ein. Die Einlasstore \u00f6ffnen 15 Minuten vor Showbeginn.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Verbotene Gegenst\u00e4nde:<\/strong> Im Sitzbereich sind keine Speisen, Getr\u00e4nke oder Glasflaschen erlaubt. Haustiere sind in der Veranstaltungsst\u00e4tte nicht gestattet.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Sicherheitsma\u00dfnahmen:<\/strong> Kinder m\u00fcssen st\u00e4ndig beaufsichtigt werden und es ist den Besuchern nicht gestattet, sich an den Beckenrand zu lehnen oder dort aufzuhalten.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Respekt vor Tieren:<\/strong> Ber\u00fchren oder st\u00f6ren Sie die Delfine und Robben nicht, es sei denn, Sie nehmen an bestimmten Aktivit\u00e4ten wie Schwimmen oder Fototerminen teil.<\/span><\/li><\/ol><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1127\" aria-expanded=\"false\">Ausstattung und Zugang<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1127\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1127\" tabindex=\"0\" hidden=\"hidden\"><h3><span style=\"color: #000000;\">Ausstattung und Zugang<\/span><\/h3><ul><li><span style=\"color: #000000;\"><strong>Bestuhlungsm\u00f6glichkeiten:<\/strong> W\u00e4hlen Sie zwischen VVIP (Reihe A), VIP (Reihe B), Deluxe (Reihe CD) oder Regular (Reihe EG).<\/span><\/li><li><span style=\"color: #000000;\"><strong>Rollstuhlzug\u00e4nglichkeit:<\/strong> Der Veranstaltungsort ist f\u00fcr Rollstuhlfahrer zug\u00e4nglich und das Personal steht Ihnen bei Fragen gerne zur Verf\u00fcgung.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Parken:<\/strong> F\u00fcr Besucher stehen kostenlose Parkpl\u00e4tze direkt am Veranstaltungsort zur Verf\u00fcgung.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Toiletten:<\/strong> Vor Ort stehen saubere und barrierefreie Toiletten zur Verf\u00fcgung.<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1128\" aria-expanded=\"false\">Tipps<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1128\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1128\" tabindex=\"0\" hidden=\"hidden\"><h3><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2859\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Swimming-With-Dolphin-Phuket.jpg\" alt=\"Schwimmen mit Delfinen in Phuket\" width=\"296\" height=\"222\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Swimming-With-Dolphin-Phuket.jpg 1478w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Swimming-With-Dolphin-Phuket-768x576.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Swimming-With-Dolphin-Phuket-400x300.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Swimming-With-Dolphin-Phuket-600x450.jpg 600w\" sizes=\"(max-width: 296px) 100vw, 296px\" \/><\/span><\/h3><h3><span style=\"color: #000000;\">Tipps<\/span><\/h3><ul><li><span style=\"color: #000000;\">Kommen Sie mindestens 30 Minuten vor Beginn der Show, um Ihre Pl\u00e4tze zu sichern und Ansturm zu vermeiden.<\/span><\/li><li><span style=\"color: #000000;\">Vergessen Sie nicht, Ihre Kamera mitzubringen, um unvergessliche Momente mit den Delfinen festzuhalten.<\/span><\/li><li><span style=\"color: #000000;\">F\u00fcr das Schwimmen mit Delfinen ist eine Voranmeldung erforderlich. Reservieren Sie Ihren Platz daher fr\u00fchzeitig, um Entt\u00e4uschungen zu vermeiden.<\/span><\/li><li><span style=\"color: #000000;\">Tragen Sie bequeme Kleidung und seien Sie auf rutschigen Oberfl\u00e4chen im Poolbereich vorsichtig.<\/span><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1129\" aria-expanded=\"false\">Speisem\u00f6glichkeiten<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1129\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1129\" tabindex=\"0\" hidden=\"hidden\"><h3><span style=\"color: #000000;\">Speisem\u00f6glichkeiten<\/span><\/h3><p><span style=\"color: #000000;\">W\u00e4hrend die Dolphin Show kein eigenes Restaurant hat, bieten nahe gelegene Restaurants eine Auswahl an lokalen und internationalen Gerichten. Restaurants, die sich perfekt f\u00fcr eine Mahlzeit vor oder nach der Show eignen, sind nur eine kurze Autofahrt vom Veranstaltungsort entfernt.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a9c455f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9c455f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d8f4ab\" data-id=\"7d8f4ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-295f44f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"295f44f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6b33032\" data-id=\"6b33032\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d36d5e0 elementor-widget elementor-widget-heading\" data-id=\"d36d5e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Warum sollten Sie Ihre Tickets f\u00fcr Dolphins Bay Phuket online kaufen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6611c4 elementor-widget elementor-widget-text-editor\" data-id=\"b6611c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Buchen Sie Ihren <a href=\"https:\/\/ancientcitybangkok.com\/de\">Dolphins Bay Phuket Tickets<\/a> Online bietet eine Vielzahl von Vorteilen, die Ihr Gesamterlebnis verbessern. In erster Linie garantiert die Online-Buchung Ihrer Tickets Ihren Platz bei dieser beliebten Attraktion und stellt sicher, dass Sie die atemberaubenden Delfin- und Robbenshows, die Besucher aus aller Welt in ihren Bann ziehen, nicht verpassen. Wenn Sie Ihre Tickets online kaufen, profitieren Sie auch von exklusiven Rabatten, die am Ticketschalter oft nicht erh\u00e4ltlich sind. So sparen Sie Geld und genie\u00dfen gleichzeitig eine Weltklasse-Auff\u00fchrung. Die bequeme Online-Buchung erm\u00f6glicht es Ihnen, Ihren Besuch im Voraus zu planen und lange Warteschlangen und Entt\u00e4uschungen in letzter Minute zu vermeiden. Dar\u00fcber hinaus bieten Online-Buchungen flexible Optionen, z. B. die Auswahl bevorzugter Sitzpl\u00e4tze, einschlie\u00dflich VIP- und VVIP-Sitzpl\u00e4tze f\u00fcr ein Premium-Erlebnis mit der besten Aussicht. Mit sofortiger Best\u00e4tigung und mobilen Tickets wird der Prozess optimiert, sodass Sie sich darauf konzentrieren k\u00f6nnen, Erinnerungen mit diesen erstaunlichen Meeresbewohnern zu schaffen. Schlie\u00dflich k\u00f6nnen Sie sicher sein, dass alle Details, einschlie\u00dflich Spielzeiten und wichtiger Besucherinformationen, leicht zug\u00e4nglich sind, sodass Ihr Tag bei <a href=\"https:\/\/ancientcitybangkok.com\/de\">Dolphins Bay Phuket<\/a> reibungslos und problemlos.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-d5a9ad5 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5a9ad5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-601c6fd\" data-id=\"601c6fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19c3e8c elementor-widget elementor-widget-heading\" data-id=\"19c3e8c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Warum sollten Sie Safari World Bangkok besuchen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-138d684 elementor-widget elementor-widget-shortcode\" data-id=\"138d684\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">[benutzerdefinierter Schieberegler]<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf7014f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf7014f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-182ba96\" data-id=\"182ba96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7c72c7 elementor-widget elementor-widget-heading\" data-id=\"f7c72c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Dual Park Abenteuer\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dd668c elementor-widget elementor-widget-text-editor\" data-id=\"3dd668c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFahren Sie mit der Stra\u00dfenbahn durch den Safari Park und sehen Sie Tausende pelziger Freunde in ihren nachgebildeten Lebensr\u00e4umen. Stellen Sie sich vor, Sie sehen Giraffen, die direkt aus Ihrem Stra\u00dfenbahnfenster nach Bl\u00e4ttern greifen, oder L\u00f6wen, die am Wegesrand faulenzen. Tauchen Sie dann in den Marine Park ein, der unglaubliche Wasserlebewesen und Tiershows beherbergt. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1fa6b16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fa6b16\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddd7133\" data-id=\"ddd7133\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-e221464 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e221464\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-35bbc21\" data-id=\"35bbc21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6790bf6 elementor-widget elementor-widget-heading\" data-id=\"6790bf6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Warum sollten Sie Dolphins Bay Phuket besuchen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af4a05f elementor-widget elementor-widget-text-editor\" data-id=\"af4a05f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Dolphins Bay Phuket bietet Besuchern jeden Alters ein unvergessliches Erlebnis, bei dem Sie die unglaubliche Intelligenz und den Charme der Delfine aus n\u00e4chster N\u00e4he erleben k\u00f6nnen. Die gut kuratierten Shows zeigen nicht nur Delfine, sondern auch Robben und bieten eine spannende und herzerw\u00e4rmende Vorf\u00fchrung von Talent und Spa\u00df im Wasser. Besucher haben die einmalige Gelegenheit, mit Delfinen zu schwimmen, was es zu einem unvergesslichen und interaktiven Abenteuer macht. Dolphins Bay Phuket ist perfekt f\u00fcr Familien, Paare und Alleinreisende und ist mehr als nur eine Show \u2013 es ist ein Erlebnis voller Freude, Lernen und Ehrfurcht. Die hochmoderne Anlage, die praktischen Showzeiten und die familienfreundliche Umgebung machen es zu einer Attraktion, die Sie auf Ihrer Reise nach Phuket unbedingt besuchen m\u00fcssen. Egal, ob Sie Meerestiere bei ihren Darbietungen sehen m\u00f6chten oder eine pers\u00f6nliche Begegnung aus n\u00e4chster N\u00e4he suchen, Dolphins Bay Phuket bietet alles auf spektakul\u00e4re Weise.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f3d1d34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3d1d34\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69a6f34\" data-id=\"69a6f34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3024455 elementor-widget elementor-widget-heading\" data-id=\"3024455\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aktivit\u00e4ten in Dolphins Bay Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13f37e9 elementor-widget elementor-widget-text-editor\" data-id=\"13f37e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Entdecken Sie ein unvergessliches Meereserlebnis mit einer Reihe spannender Aktivit\u00e4ten f\u00fcr alle Altersgruppen im Dolphins Bay Phuket.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-20f2020 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20f2020\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ea62efb\" data-id=\"ea62efb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d864c62 elementor-widget elementor-widget-image\" data-id=\"d864c62\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/elementor\/thumbs\/Dolphin-Phuket-qw1d9mgox8tyc9uigdeme812x5tvnv3ouyialyfws8.jpg\" title=\"Dolphin Phuket\" alt=\"Dolphin Phuket\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-613e04a elementor-widget elementor-widget-heading\" data-id=\"613e04a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Delfinshow<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-488fa9e elementor-widget elementor-widget-text-editor\" data-id=\"488fa9e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Der <strong>Delfinshow<\/strong> ist die Hauptattraktion in Dolphins Bay Phuket, wo gut trainierte Delfine und Robben eine unglaubliche Show voller Beweglichkeit, Intelligenz und Charme bieten. Besucher k\u00f6nnen ein 40-min\u00fctiges Spektakel mit beeindruckender Akrobatik, synchronisierten Bewegungen und spielerischen Interaktionen zwischen den Trainern und den Delfinen genie\u00dfen. Es ist ein unterhaltsames Erlebnis f\u00fcr die ganze Familie und eine einzigartige Gelegenheit, die unglaubliche Bindung zwischen Menschen und Delfinen zu erleben.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cbf8f56\" data-id=\"cbf8f56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-698017f elementor-widget elementor-widget-image\" data-id=\"698017f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/elementor\/thumbs\/Dolphin-Show-Phuket-Tickets-qw1dd0nplph89kx0mu84ed70593lgiksnrbezxeqbc.jpg\" title=\"Tickets f\u00fcr die Delfinshow in Phuket\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a67377 elementor-widget elementor-widget-heading\" data-id=\"1a67377\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Fotos mit Delfinen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c43eb76 elementor-widget elementor-widget-text-editor\" data-id=\"c43eb76\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Nach dem Genuss der Delfinshow k\u00f6nnen die Besucher bleibende Erinnerungen sammeln mit dem <strong>Fotos mit Delfinen<\/strong> Sitzung. Dieses interaktive Erlebnis erm\u00f6glicht es Ihnen, den Delfinen ganz nahe zu kommen und den Moment mit einem professionellen Fotografen festzuhalten. Ob Sie mit einem Delfin posieren oder mit ihm planschen, diese Fotos sind ein perfektes Andenken an Ihren Besuch in Dolphins Bay.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ca88db2\" data-id=\"ca88db2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2914ffb elementor-widget elementor-widget-image\" data-id=\"2914ffb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/elementor\/thumbs\/Dolphin-Show-Phuket-Ticket-qw1dez5lua5qgc2m76p53dekp5g4htcnxg8tzoi7co.jpg\" title=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" alt=\"Eintrittskarte f\u00fcr die Delfinshow in Phuket\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f592622 elementor-widget elementor-widget-heading\" data-id=\"f592622\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Magische Ber\u00fchrung<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa41eae elementor-widget elementor-widget-text-editor\" data-id=\"aa41eae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Der <strong>Magische Ber\u00fchrung<\/strong> Die Aktivit\u00e4t bietet eine besondere Gelegenheit, die Delfine unter fachkundiger Aufsicht zu ber\u00fchren und mit ihnen zu interagieren. Dieses praktische Erlebnis erm\u00f6glicht es den Besuchern, auf sichere und lehrreiche Weise mit diesen majest\u00e4tischen Meeresbewohnern in Kontakt zu treten. Die G\u00e4ste werden durch den Prozess gef\u00fchrt, wobei sowohl ihre Sicherheit als auch das Wohlergehen der Delfine w\u00e4hrend dieser magischen Begegnung gew\u00e4hrleistet sind.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-4246b04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4246b04\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b5335c1\" data-id=\"b5335c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca5220e elementor-widget elementor-widget-image\" data-id=\"ca5220e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Price.jpg\" class=\"attachment-large size-large wp-image-2844\" alt=\"Delfinshow Phuket Preis\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Price.jpg 2000w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Price-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Price-1536x1025.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Price-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Price-600x400.jpg 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0681b4f elementor-widget elementor-widget-heading\" data-id=\"0681b4f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Junger Trainer<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3842cbe elementor-widget elementor-widget-text-editor\" data-id=\"3842cbe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">F\u00fcr diejenigen, die erleben m\u00f6chten, wie es ist, sich um Delfine zu k\u00fcmmern, <strong>Junger Trainer<\/strong> Das Programm erm\u00f6glicht es Ihnen, einen Tag lang in die Rolle eines Delfintrainers zu schl\u00fcpfen. Bei dieser einzigartigen Aktivit\u00e4t lernen die Teilnehmer das Verhalten von Delfinen, F\u00fctterungsroutinen und grundlegende Trainingstechniken kennen. Es ist eine lehrreiche und umfassende Erfahrung, die Einblicke in das Leben der Trainer und der Delfine bietet, die sie betreuen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-340d562\" data-id=\"340d562\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9e57f2 elementor-widget elementor-widget-image\" data-id=\"b9e57f2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1366\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.jpg\" class=\"attachment-large size-large wp-image-2841\" alt=\"\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price.jpg 2048w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price-1536x1025.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-Ticket-Price-600x400.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4bcc49 elementor-widget elementor-widget-heading\" data-id=\"c4bcc49\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Gl\u00fcckliche Zeit<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33c92a9 elementor-widget elementor-widget-text-editor\" data-id=\"33c92a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>Gl\u00fcckliche Zeit<\/strong> Im Dolphins Bay Phuket erwartet Sie die ultimative Aktivit\u00e4t, bei der Besucher mit Delfinen schwimmen und die direkte Interaktion im Wasser genie\u00dfen k\u00f6nnen. Dies ist eine einmalige Gelegenheit, spielerische Momente zu teilen und eine Bindung zu diesen erstaunlichen Tieren in ihrem Element aufzubauen. Egal, ob Sie ein guter Schwimmer sind oder einfach nur nebenher treiben m\u00f6chten, diese Aktivit\u00e4t garantiert ein unterhaltsames und unvergessliches Erlebnis.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8c4ceee\" data-id=\"8c4ceee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-02326ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02326ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f31b6c5\" data-id=\"f31b6c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-bf884a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf884a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3e243ee\" data-id=\"3e243ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-746a95e elementor-widget elementor-widget-heading\" data-id=\"746a95e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entdecken Sie spannende Aktivit\u00e4ten im Dolphins Bay Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-198f8ea elementor-widget elementor-widget-text-editor\" data-id=\"198f8ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Im Dolphins Bay Phuket finden Sie eine Reihe spannender und herzerw\u00e4rmender Aktivit\u00e4ten f\u00fcr Besucher jeden Alters. Von atemberaubenden Delfinshows bis hin zur Begegnung mit diesen intelligenten Lebewesen aus n\u00e4chster N\u00e4he verspricht Ihr Besuch unvergesslich zu werden.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-cbdc388 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbdc388\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b65f5f6\" data-id=\"b65f5f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-bf2bd38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf2bd38\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d5f08fb\" data-id=\"d5f08fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1604ecf elementor-widget elementor-widget-heading\" data-id=\"1604ecf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Was k\u00f6nnen Sie im Dolphins Bay Phuket unternehmen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a09b2b elementor-widget elementor-widget-text-editor\" data-id=\"9a09b2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Im Dolphins Bay Phuket k\u00f6nnen Sie an einer Vielzahl von Aktivit\u00e4ten teilnehmen, die unterhaltsam und lehrreich sind. Egal, ob Sie sich bei einer Show entspannen oder mit Delfinen interagieren m\u00f6chten, es ist f\u00fcr jeden etwas dabei.<\/span><\/p><ul><li><span style=\"color: #000000;\"><strong>Delfinshow:<\/strong> Bewundern Sie die unglaubliche Akrobatik und die Stunts der Delfine, die ihre Intelligenz und ihr verspieltes Wesen zur Schau stellen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Magic Touch-Erlebnis:<\/strong> Nutzen Sie die einmalige Gelegenheit, Delfine aus n\u00e4chster N\u00e4he zu ber\u00fchren, mit ihnen zu interagieren und ihren sanften Geist zu sp\u00fcren.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Young Trainer Programm:<\/strong> Erlernen Sie die Kunst der Kommunikation mit Delfinen und erleben Sie, wie es ist, einen Tag lang Trainer zu sein.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Fotosessions:<\/strong> Halten Sie Erinnerungen mit Delfinen in lustigen und personalisierten Fotosessions fest.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Schwimmen mit Delfinen:<\/strong> Wagen Sie den Sprung ins Wasser und schwimmen Sie neben diesen anmutigen Kreaturen. Es ist ein spannendes und lehrreiches Erlebnis.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-74f6b59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74f6b59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dc177d\" data-id=\"9dc177d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f6a2f23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6a2f23\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4fad384\" data-id=\"4fad384\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6abf05a elementor-widget elementor-widget-heading\" data-id=\"6abf05a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00dcber Dolphins Bay Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de1a0bf elementor-widget elementor-widget-text-editor\" data-id=\"de1a0bf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Dolphins Bay Phuket ist das einzige Delfinarium in Phuket und bietet Besuchern die au\u00dfergew\u00f6hnliche Gelegenheit, diese bemerkenswerten Meeress\u00e4uger in einer lebendigen und aufregenden Umgebung zu erleben. Die Einrichtung legt Wert auf Bildung, Schutz und Interaktion und ist somit ein perfektes familienfreundliches Reiseziel. Dolphins Bay Phuket bietet t\u00e4glich Shows, bei denen Delfine und Robben beeindruckende Routinen und Tricks vorf\u00fchren.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-abfda9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abfda9c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87ed94c\" data-id=\"87ed94c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-3955082 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3955082\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-413cedf\" data-id=\"413cedf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dedc754 elementor-widget elementor-widget-heading\" data-id=\"dedc754\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Delfinshows<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd39c64 elementor-widget elementor-widget-text-editor\" data-id=\"bd39c64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Es gibt t\u00e4glich drei Showzeiten \u2013 11:00 Uhr, 14:00 Uhr und 17:00 Uhr \u2013 au\u00dfer montags, wenn das Delfinarium geschlossen ist. Jede Show besteht aus einer Robbenvorf\u00fchrung, gefolgt von einer Delfin-Extravaganz, die Unterhaltung und Bildung vereint. Lassen Sie sich von der Akrobatik, den Tricks und der Intelligenz dieser entz\u00fcckenden Meeress\u00e4uger \u00fcberraschen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-196fbfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"196fbfc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fdff5b\" data-id=\"6fdff5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-769e340 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"769e340\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7422f2d\" data-id=\"7422f2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abb9455 elementor-widget elementor-widget-heading\" data-id=\"abb9455\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Regeln f\u00fcr ein sicheres und angenehmes Erlebnis<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccbf162 elementor-widget elementor-widget-text-editor\" data-id=\"ccbf162\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Um ein reibungsloses und angenehmes Erlebnis f\u00fcr alle zu gew\u00e4hrleisten, hat Dolphins Bay Phuket mehrere wichtige Regeln eingef\u00fchrt:<\/span><\/p><ol><li><span style=\"color: #000000;\">Der Einlass erfolgt 15 Minuten vor jeder Show.<\/span><\/li><li><span style=\"color: #000000;\">Warten Sie mit dem Betreten, bis die Robbenshow vorbei ist.<\/span><\/li><li><span style=\"color: #000000;\">Setzen Sie sich entsprechend Ihrer zugewiesenen Ticketnummer.<\/span><\/li><li><span style=\"color: #000000;\">Im Sitzbereich sind keine Gl\u00e4ser und Flaschen erlaubt.<\/span><\/li><li><span style=\"color: #000000;\">Kinder sollten sich nicht in der N\u00e4he des Beckenrandes aufhalten und Haustiere sind nicht gestattet.<\/span><\/li><li><span style=\"color: #000000;\">Innerhalb der Anlage besteht Rauchverbot.<\/span><\/li><li><span style=\"color: #000000;\">Befolgen Sie alle Richtlinien bez\u00fcglich Sicherheit und Umgang mit den Tieren.<\/span><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6bb16d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bb16d2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16d41a9\" data-id=\"16d41a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2561aab elementor-widget elementor-widget-heading\" data-id=\"2561aab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Shows im Dolphins Bay Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4beef53 elementor-widget elementor-widget-text-editor\" data-id=\"4beef53\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Erleben Sie die Magie des Meereslebens mit unserer aufregenden Robben- und Delfinshow sowie den interaktiven Schwimm- und Interaktionssitzungen, die alle darauf ausgelegt sind, Besucher jeden Alters zu faszinieren.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-ebb0a6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebb0a6c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-994247b\" data-id=\"994247b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce4a937 elementor-widget elementor-widget-image\" data-id=\"ce4a937\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Seal-Show-Phuket.jpg\" class=\"attachment-full size-full wp-image-2845\" alt=\"Robbenshow Phuket\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Seal-Show-Phuket.jpg 1620w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Seal-Show-Phuket-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Seal-Show-Phuket-1536x1024.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Seal-Show-Phuket-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Seal-Show-Phuket-600x400.jpg 600w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe6f73 elementor-widget elementor-widget-heading\" data-id=\"cbe6f73\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Robbenschau<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-236bd24 elementor-widget elementor-widget-text-editor\" data-id=\"236bd24\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Der <strong>Robbenschau<\/strong> ist ein herrlicher Vorakt, bei dem Robben ihre verspielten Pers\u00f6nlichkeiten und erstaunlichen Tricks zeigen. Beobachten Sie, wie diese intelligenten Kreaturen B\u00e4lle balancieren, dem Publikum zuwinken und synchrone Darbietungen mit ihren Trainern durchf\u00fchren. Diese 15-min\u00fctige Show gibt den Ton f\u00fcr einen aufregenden Tag in Dolphins Bay Phuket an und ist perfekt f\u00fcr Besucher, die gerne Tieren dabei zusehen, wie sie ihre Talente zur Schau stellen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4532595\" data-id=\"4532595\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce3ac55 elementor-widget elementor-widget-image\" data-id=\"ce3ac55\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-scaled.jpg\" class=\"attachment-full size-full wp-image-2846\" alt=\"Delphin-Show-Preis\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-scaled.jpg 2560w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-1536x1025.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-2048x1367.jpg 2048w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Price-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06055b1 elementor-widget elementor-widget-heading\" data-id=\"06055b1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Delfinshow<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-290dbbc elementor-widget elementor-widget-text-editor\" data-id=\"290dbbc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Der <strong>Delfinshow<\/strong> ist das Highlight von Dolphins Bay Phuket. Genie\u00dfen Sie eine 30-min\u00fctige Vorf\u00fchrung von Anmut, Beweglichkeit und Intelligenz, w\u00e4hrend Delfine durch Reifen springen, synchron Saltos vollf\u00fchren und mit ihren Trainern interagieren. Diese Show bietet einen hautnahen Einblick in die Verbindung zwischen Mensch und Delfin und ist somit ein unvergessliches Erlebnis f\u00fcr alle Besucher.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-13928c6\" data-id=\"13928c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85a7517 elementor-widget elementor-widget-image\" data-id=\"85a7517\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1824\" height=\"1290\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dophin-Show-Tickets.jpg\" class=\"attachment-full size-full wp-image-2848\" alt=\"Eintrittskarten f\u00fcr die Delfinshow\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dophin-Show-Tickets.jpg 1824w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dophin-Show-Tickets-768x543.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dophin-Show-Tickets-1536x1086.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dophin-Show-Tickets-400x283.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dophin-Show-Tickets-600x424.jpg 600w\" sizes=\"(max-width: 1824px) 100vw, 1824px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1baa46 elementor-widget elementor-widget-heading\" data-id=\"a1baa46\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Schwimmen &amp; Interaktion<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ced361 elementor-widget elementor-widget-text-editor\" data-id=\"2ced361\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">F\u00fcr diejenigen, die ein intensiveres Erlebnis suchen, ist das <strong>Schwimmen &amp; Interaktion<\/strong> Bei dieser Sitzung k\u00f6nnen Sie mit Delfinen ins Wasser gehen. Unter Anleitung professioneller Trainer bietet diese Aktivit\u00e4t eine sichere und aufregende Gelegenheit, mit Delfinen zu interagieren, zu schwimmen und sogar mit ihnen zu spielen. So schaffen Sie Erinnerungen, die ein Leben lang halten. Dies ist eine ideale Option f\u00fcr Familien und Einzelpersonen, die eine einzigartige und pers\u00f6nliche Verbindung mit dem Meeresleben suchen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e122c7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e122c7b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f11cbd\" data-id=\"3f11cbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b97468c elementor-widget elementor-widget-heading\" data-id=\"b97468c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Top-Aktivit\u00e4ten in Dolphins Bay Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8219dc0 elementor-widget elementor-widget-text-editor\" data-id=\"8219dc0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #000000;\"><strong>Sehen Sie sich die spektakul\u00e4ren Delfin- und Robbenshows an<\/strong><\/span><\/li><li><span style=\"color: #000000;\"><strong>Machen Sie nach der Show Fotos mit Delfinen<\/strong><\/span><\/li><li><span style=\"color: #000000;\"><strong>Nehmen Sie am Young Trainer Programm teil<\/strong><\/span><\/li><li><span style=\"color: #000000;\"><strong>Erleben Sie die magische Ber\u00fchrung<\/strong><\/span><\/li><li><span style=\"color: #000000;\"><strong>Schwimmen Sie mit Delfinen f\u00fcr ein unvergessliches Abenteuer<\/strong><\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-28fde1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28fde1f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-04bf08d\" data-id=\"04bf08d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4066c4a elementor-widget elementor-widget-heading\" data-id=\"4066c4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Es erwarten Sie unvergessliche Momente: Tauchen Sie ein in die Magie von Dolphins Bay Phuket!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-241cd55 elementor-widget elementor-widget-text-editor\" data-id=\"241cd55\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">Erleben Sie die Top-Highlights in Dolphins Bay Phuket, darunter faszinierende Delfinshows, interaktive Schwimmsitzungen und magische Fotogelegenheiten f\u00fcr einen Tag voller Spa\u00df und Wunder.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4f36609\" data-id=\"4f36609\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-0bbe5c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bbe5c3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d52c126\" data-id=\"d52c126\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10845b9 elementor-widget elementor-widget-image\" data-id=\"10845b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1616\" height=\"1080\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.jpg\" class=\"attachment-full size-full wp-image-2850\" alt=\"Delfinshow Phuket\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.jpg 1616w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-768x513.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-1536x1027.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket-600x401.jpg 600w\" sizes=\"(max-width: 1616px) 100vw, 1616px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d7d3962\" data-id=\"d7d3962\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca58832 elementor-widget elementor-widget-image\" data-id=\"ca58832\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1567\" height=\"1045\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Tickets-Phuket.jpg\" class=\"attachment-full size-full wp-image-2851\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Tickets-Phuket.jpg 1567w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Tickets-Phuket-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Tickets-Phuket-1536x1024.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Tickets-Phuket-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Tickets-Phuket-600x400.jpg 600w\" sizes=\"(max-width: 1567px) 100vw, 1567px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-2caeb9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2caeb9f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d627e56\" data-id=\"d627e56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e431dc3 elementor-widget elementor-widget-image\" data-id=\"e431dc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"650\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.jpg\" class=\"attachment-large size-large wp-image-2852\" alt=\"Tickets f\u00fcr Dolphins Bay Phuket\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets.jpg 1181w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets-768x423.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets-400x220.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Tickets-600x330.jpg 600w\" sizes=\"(max-width: 1181px) 100vw, 1181px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9453983\" data-id=\"9453983\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d20fa47 elementor-widget elementor-widget-image\" data-id=\"d20fa47\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2168\" height=\"1219\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show.jpg\" class=\"attachment-large size-large wp-image-2853\" alt=\"Phuket Delfinshow\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show.jpg 2168w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-768x432.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-1536x864.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-2048x1152.jpg 2048w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-800x450.jpg 800w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-400x225.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-600x337.jpg 600w\" sizes=\"(max-width: 2168px) 100vw, 2168px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-b7a5f6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7a5f6f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64ef790\" data-id=\"64ef790\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0551d7a elementor-widget elementor-widget-heading\" data-id=\"0551d7a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ticketoptionen f\u00fcr Dolphins Bay Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab17259 elementor-widget elementor-widget-text-editor\" data-id=\"ab17259\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Es gibt mehrere Ticketoptionen f\u00fcr unterschiedliche Vorlieben:<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2864 alignleft\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Seats.jpg\" alt=\"Sitzpl\u00e4tze im Dolphins Bay Phuket\" width=\"512\" height=\"361\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Seats.jpg 2048w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Seats-768x541.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Seats-1536x1082.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Seats-400x282.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-Phuket-Seats-600x423.jpg 600w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p><ul><li><span style=\"color: #000000;\"><strong>VVIP-Sitzplatzkarten (Reihe A)<\/strong>: F\u00fcr die beste Sicht auf die Auff\u00fchrungen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>VIP-Sitzplatz-Tickets (Reihe B)<\/strong>: Nah genug am Geschehen und dennoch mit erstklassigen Sitzpl\u00e4tzen.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Deluxe-Sitzplatz-Tickets (Reihen C und D)<\/strong>: Preiswerte Sitze f\u00fcr eine ausgewogene Sicht.<\/span><\/li><li><span style=\"color: #000000;\"><strong>Normale Sitzplatzkarten (Reihen E, F und G)<\/strong>: Erschwingliche und dennoch bequeme Sitzgelegenheiten f\u00fcr alle.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-661c3fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"661c3fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-929c10d\" data-id=\"929c10d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c43233 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c43233\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-af5f3ea\" data-id=\"af5f3ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4fcd24 elementor-widget elementor-widget-heading\" data-id=\"e4fcd24\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Beste Angebote und Rabatte auf Tickets f\u00fcr die Delfinshow in Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-490f0e0 elementor-widget elementor-widget-text-editor\" data-id=\"490f0e0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Wenn Sie Ihre Tickets online \u00fcber unsere Plattform buchen, erhalten Sie exklusive Rabatte und Pauschalangebote. Genie\u00dfen Sie die besten Preise auf <a href=\"https:\/\/ancientcitybangkok.com\/de\">Dolphins Bay Phuket Tickets<\/a>, mit Optionen zur Verbesserung Ihres Erlebnisses, von Premium-Sitzen bis hin zu besonderen Interaktionen wie Schwimmen mit Delfinen oder dem Young Trainer-Programm.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-51e748a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51e748a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3282088\" data-id=\"3282088\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24c7808 elementor-widget elementor-widget-heading\" data-id=\"24c7808\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Was k\u00f6nnen Sie im Dolphins Bay Phuket unternehmen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5e5bd83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e5bd83\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9a675f7\" data-id=\"9a675f7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cf2239 elementor-widget elementor-widget-heading\" data-id=\"0cf2239\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Endlose Abenteuer erwarten Sie: Entdecken Sie das Beste von Dolphins Bay Phuket!<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a65d79 elementor-widget elementor-widget-text-editor\" data-id=\"5a65d79\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">Entdecken Sie im Dolphins Bay Phuket eine Welt voller unvergesslicher Aktivit\u00e4ten und Erlebnisse, von atemberaubenden Delfinvorf\u00fchrungen bis hin zu praktischen Interaktionen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b84563\" data-id=\"4b84563\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-403c7aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"403c7aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fd1289e\" data-id=\"fd1289e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a25e163 elementor-widget elementor-widget-image\" data-id=\"a25e163\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-scaled.jpg\" class=\"attachment-full size-full wp-image-2855\" alt=\"Delfinbucht\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-scaled.jpg 2560w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-1536x1024.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-2048x1365.jpg 2048w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphins-Bay-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d0b3ea\" data-id=\"0d0b3ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e47212 elementor-widget elementor-widget-image\" data-id=\"3e47212\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1566\" height=\"1046\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-Tickets.jpg\" class=\"attachment-large size-large wp-image-2856\" alt=\"Tickets f\u00fcr die Delfinshow in Phuket\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-Tickets.jpg 1566w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-Tickets-768x513.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-Tickets-1536x1026.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-Tickets-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphin-Show-Tickets-600x401.jpg 600w\" sizes=\"(max-width: 1566px) 100vw, 1566px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-a5fcb92 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5fcb92\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07701d3\" data-id=\"07701d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52ba55e elementor-widget elementor-widget-image\" data-id=\"52ba55e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1568\" height=\"1044\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphins-Bay.jpg\" class=\"attachment-large size-large wp-image-2857\" alt=\"Phuket Dolphins Bay\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphins-Bay.jpg 1568w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphins-Bay-768x511.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphins-Bay-1536x1023.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphins-Bay-400x266.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Dolphins-Bay-600x399.jpg 600w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2be94af\" data-id=\"2be94af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3da04ee elementor-widget elementor-widget-image\" data-id=\"3da04ee\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Show-Dolphins-Bay-scaled.jpg\" class=\"attachment-large size-large wp-image-2858\" alt=\"Dolphins Bay anzeigen\" srcset=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Show-Dolphins-Bay-scaled.jpg 2560w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Show-Dolphins-Bay-768x512.jpg 768w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Show-Dolphins-Bay-1536x1024.jpg 1536w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Show-Dolphins-Bay-2048x1365.jpg 2048w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Show-Dolphins-Bay-400x267.jpg 400w, https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Show-Dolphins-Bay-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-16f59d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16f59d0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c677462\" data-id=\"c677462\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f2953d elementor-widget elementor-widget-heading\" data-id=\"3f2953d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Top-Sehensw\u00fcrdigkeiten in der N\u00e4he von Dolphins Bay Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c445d4 elementor-widget elementor-widget-text-editor\" data-id=\"2c445d4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Hier ist eine detaillierte Liste der wichtigsten Sehensw\u00fcrdigkeiten in der N\u00e4he von Dolphins Bay Phuket, die Sie bei einem Tag voller Abenteuer und kultureller Erlebnisse in Chalong, Phuket, erkunden k\u00f6nnen:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-237a1a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"237a1a6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-37b1b07\" data-id=\"37b1b07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c945e5b elementor-widget elementor-widget-image\" data-id=\"c945e5b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"381\" height=\"200\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Big-Buddha-Phuket.png\" class=\"attachment-full size-full wp-image-2888\" alt=\"Gro\u00dfer Buddha von Phuket\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf9b94 elementor-widget elementor-widget-heading\" data-id=\"5bf9b94\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Gro\u00dfer Buddha von Phuket<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e41b5ae elementor-widget elementor-widget-text-editor\" data-id=\"e41b5ae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Eines der ber\u00fchmtesten Wahrzeichen von Phuket, das <strong>Gro\u00dfer Buddha<\/strong> steht in einer H\u00f6he von 45 Metern auf dem Nakkerd Hill. Es bietet einen atemberaubenden Panoramablick auf Phuket Town, Kata, die Str\u00e4nde von Karon und die Chalong Bay. Diese ruhige Statue ist ein Ort der Anbetung und Meditation und zieht Besucher aus aller Welt an, die ihre spirituelle und friedliche Atmosph\u00e4re erleben m\u00f6chten. Die Umgebung ist voller buddhistischer Schreine und friedlicher G\u00e4rten, was sie zu einem gro\u00dfartigen Ort zum Entspannen und Nachdenken macht. Verpassen Sie nicht die Gelegenheit, atemberaubende Fotos mit dem bekanntesten Symbol der Insel zu machen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-028a0cd\" data-id=\"028a0cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-799d23e elementor-widget elementor-widget-image\" data-id=\"799d23e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"381\" height=\"200\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Wat-Chalong-Chalong-Temple.png\" class=\"attachment-full size-full wp-image-2892\" alt=\"Wat Chalong (Chalong-Tempel)\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa3c970 elementor-widget elementor-widget-heading\" data-id=\"fa3c970\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Wat Chalong (Chalong-Tempel)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9f0dad elementor-widget elementor-widget-text-editor\" data-id=\"e9f0dad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>Wat Chalong<\/strong>, einer der am meisten verehrten Tempel Phukets, liegt ganz in der N\u00e4he von Dolphins Bay. Es ist ein wundersch\u00f6ner buddhistischer Tempel, historisch bedeutsam und sowohl bei Touristen als auch bei Einheimischen beliebt. Wat Chalong ist ber\u00fchmt f\u00fcr seine komplexe Architektur, seine friedlichen G\u00e4rten und seine spirituelle Bedeutung. Im Haupttempel finden Sie Reliquien des verehrten M\u00f6nchs Luang Por Cham, die eine Anlaufstelle f\u00fcr Segenssuchende sind. Auf dem Tempelgel\u00e4nde befindet sich auch eine beeindruckende Pagode, die mit atemberaubenden Wandmalereien geschm\u00fcckt ist, die das Leben Buddhas darstellen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6b1c50a\" data-id=\"6b1c50a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5abe23c elementor-widget elementor-widget-image\" data-id=\"5abe23c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"381\" height=\"200\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Chalong-Pier.png\" class=\"attachment-full size-full wp-image-2889\" alt=\"Chalong Pier\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9317fd elementor-widget elementor-widget-heading\" data-id=\"d9317fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Chalong Pier<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79a487f elementor-widget elementor-widget-text-editor\" data-id=\"79a487f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>Chalong Pier<\/strong> ist der Ausgangspunkt f\u00fcr viele Bootstouren zu den nahegelegenen Inseln wie Coral Island und Racha Island. Dieser belebte Pier liegt nur eine kurze Fahrt von Dolphins Bay Phuket entfernt und ist ein Ausgangspunkt f\u00fcr Tagesausfl\u00fcge, Tauchausfl\u00fcge und Angeltouren. Es ist ein idealer Ort f\u00fcr alle, die die Meeressch\u00f6nheit von Phuket erkunden m\u00f6chten. Egal, ob Sie einen Tauchgang planen oder einfach nur die Aussicht auf den Hafen genie\u00dfen m\u00f6chten, der Chalong Pier ist eine gro\u00dfartige Erg\u00e4nzung Ihres Tagesprogramms.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-63b369c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63b369c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c62bf0e\" data-id=\"c62bf0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad7c9a1 elementor-widget elementor-widget-image\" data-id=\"ad7c9a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"381\" height=\"200\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Zoo.png\" class=\"attachment-full size-full wp-image-2891\" alt=\"Phuket Zoo\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32812ab elementor-widget elementor-widget-heading\" data-id=\"32812ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Phuket Zoo<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d362a0 elementor-widget elementor-widget-text-editor\" data-id=\"9d362a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Eine kurze Fahrt von Dolphins Bay, <strong>Phuket Zoo<\/strong> bietet ein unterhaltsames und lehrreiches Erlebnis f\u00fcr Familien und Tierliebhaber. Der Zoo ist die Heimat einer Vielzahl exotischer Tiere, darunter Tiger, Elefanten und verschiedene Reptilien. Der Zoo bietet t\u00e4glich mehrere Shows, darunter Krokodil- und Elefantenvorf\u00fchrungen. Dies ist eine unterhaltsame M\u00f6glichkeit, Kindern den Artenschutz n\u00e4herzubringen und mehr \u00fcber die Natur zu lernen, w\u00e4hrend sie einen Tag mit der Familie genie\u00dfen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-be5ca02\" data-id=\"be5ca02\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-721f82a elementor-widget elementor-widget-image\" data-id=\"721f82a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"381\" height=\"200\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Phuket-Botanic-Garden.png\" class=\"attachment-full size-full wp-image-2890\" alt=\"Botanischer Garten Phuket\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00d0b59 elementor-widget elementor-widget-heading\" data-id=\"00d0b59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Botanischer Garten Phuket<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-971fe7c elementor-widget elementor-widget-text-editor\" data-id=\"971fe7c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">In der N\u00e4he des Chalong-Gebiets gelegen, <strong>Botanischer Garten Phuket<\/strong> ist ein friedlicher R\u00fcckzugsort f\u00fcr Naturliebhaber. Der Garten pr\u00e4sentiert Themeng\u00e4rten, darunter einen Regenwaldgarten, einen Palmengarten und einen Orchideenpavillon, und bietet Besuchern eine hervorragende Gelegenheit, Phukets vielf\u00e4ltige Flora kennenzulernen. Es ist ein ruhiger, erfrischender Ort f\u00fcr einen Spaziergang nach einem erlebnisreichen Tag in Dolphins Bay und ein perfekter Ort zum Fotografieren und Entspannen inmitten der nat\u00fcrlichen Sch\u00f6nheit der Insel.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-63c3d9e\" data-id=\"63c3d9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-99ad58e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99ad58e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df3c344\" data-id=\"df3c344\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc95077 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc95077\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f854733\" data-id=\"f854733\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a89507d elementor-widget elementor-widget-heading\" data-id=\"a89507d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bewertungen &amp; Rezensionen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0eb737c ratings reviews elementor--star-style-star_unicode elementor-arrows-yes elementor-review--has-separator elementor-widget elementor-widget-reviews\" data-id=\"0eb737c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_per_view_tablet&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-7423875\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dolphins-Bay-Phuket.png\" alt=\"Sarah R.\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Sarah R.<\/span><div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><\/div><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\"><span class=\"elementor-screen-only\">Mehr lesen<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eDolphins Bay Phuket war ein unglaubliches Erlebnis! Die Delfinshow war spektakul\u00e4r und die Trainer haben ganz offensichtlich eine tiefe Verbindung zu den Tieren. Meine Kinder liebten das Schwimmen mit den Delfinen \u2013 es war der H\u00f6hepunkt unserer Reise!\u201c\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-92578fe\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dolphins-Bay-Phuket.png\" alt=\"James S.\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">James S.<\/span><div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><\/div><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\"><span class=\"elementor-screen-only\">Mehr lesen<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t&quot;Ein unvergesslicher Tag! Das gesamte Erlebnis war gut organisiert, vom freundlichen Personal bis zur beeindruckenden Robbenshow. Ich kann es jedem, der Phuket besucht, w\u00e4rmstens empfehlen, insbesondere Familien.&quot;\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-9fc795f\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dolphins-Bay-Phuket.png\" alt=\"Maria S.\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Maria S.<\/span><div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><\/div><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\"><span class=\"elementor-screen-only\">Mehr lesen<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eIch war \u00fcberw\u00e4ltigt von der Interaktion, die wir mit den Delfinen hatten. Die Shows sind nicht nur unterhaltsam, sondern auch lehrreich. Mit den Delfinen zu schwimmen war eine einmalige Gelegenheit!\u201c\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-4ba54c8\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dolphins-Bay-Phuket.png\" alt=\"Michael K.\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Michael K.<\/span><div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><\/div><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\"><span class=\"elementor-screen-only\">Mehr lesen<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eDolphins Bay Phuket ist ein absolutes Muss! Die Trainer sind unglaublich professionell und man merkt, dass die Tiere gut versorgt sind. Die Delfinfotos und die magische Ber\u00fchrung haben meinen Ausflug zu etwas ganz Besonderem gemacht.\u201c\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-1daecb9\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dolphins-Bay-Phuket.png\" alt=\"Arpit G.\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Arpit G.<\/span><div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><i class=\"elementor-star-full\">&#9733;<\/i><\/div><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\"><span class=\"elementor-screen-only\">Mehr lesen<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eWas f\u00fcr eine fantastische Show! Die Delfine und Robben waren unglaublich und der Veranstaltungsort war gut gepflegt. Die Kinder konnten tagelang nicht aufh\u00f6ren, davon zu reden. Es ist jeden Cent wert!\u201c\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Vorherige<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">N\u00e4chste<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f1f39f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1f39f3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64b49b0\" data-id=\"64b49b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-967bd64 elementor-widget elementor-widget-heading\" data-id=\"967bd64\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufig gestellte Fragen zu Dolphins Bay Phuket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-151b0d3 elementor-widget elementor-widget-toggle\" data-id=\"151b0d3\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2211\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was sind die Showzeiten im Dolphins Bay Phuket?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2211\"><p><span style=\"color: #000000;\">Dolphins Bay Phuket bietet t\u00e4glich drei Shows: 11:00 Uhr, 14:00 Uhr und 17:00 Uhr, au\u00dfer montags. Jede Show beginnt mit einer 15-min\u00fctigen Robbenshow, gefolgt von einer 25-min\u00fctigen Delfinshow. Die Tore \u00f6ffnen 15 Minuten vor der geplanten Showzeit.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2212\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2212\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wo liegt Dolphins Bay Phuket?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2212\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2212\"><p><span style=\"color: #000000;\">Dolphins Bay Phuket befindet sich in 33\/50, Chalong, Mueang Phuket District, Phuket 83130, Thailand. Sie k\u00f6nnen den Standort ganz einfach finden mit <a style=\"color: #000000;\" href=\"https:\/\/maps.app.goo.gl\/iKaEd3g2Nr1B9YJD8\" target=\"_new\" rel=\"noopener\">Google Maps<\/a>.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2213\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2213\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Welche Sitzm\u00f6glichkeiten gibt es?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2213\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2213\"><p><span style=\"color: #000000;\">Dolphins Bay Phuket bietet mehrere Sitzkategorien:<\/span><\/p><ul><li><span style=\"color: #000000;\"><strong>VVIP<\/strong>: Reihe A<\/span><\/li><li><span style=\"color: #000000;\"><strong>VIP<\/strong>: Reihe B<\/span><\/li><li><span style=\"color: #000000;\"><strong>Deluxe<\/strong>: Reihen C und D<\/span><\/li><li><span style=\"color: #000000;\"><strong>Regul\u00e4r<\/strong>: Reihen E, F und G<\/span><br \/><span style=\"color: #000000;\">Jede Eintrittskarte beinhaltet den Zugang zu den Robben- und Delfinshows. Die Premiumsitze bieten die beste Aussicht.<\/span><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2214\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2214\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Kann ich im Dolphins Bay Phuket mit den Delfinen schwimmen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2214\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2214\"><p><span style=\"color: #000000;\">Ja! Schwimmen mit Delfinen ist eine der einzigartigen Aktivit\u00e4ten, die angeboten werden. Es ist f\u00fcr Erwachsene und Kinder ab 6 Jahren verf\u00fcgbar. Kinder im Alter von 4 bis 5 Jahren m\u00fcssen von einem Elternteil begleitet werden und es f\u00e4llt eine zus\u00e4tzliche Geb\u00fchr an.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2215\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2215\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was sollte ich wissen, bevor ich Dolphins Bay Phuket besuche?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2215\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2215\"><p><span style=\"color: #000000;\">Bitte erscheinen Sie 15 Minuten vor Showbeginn. Rauchen ist verboten und Haustiere sowie Glasflaschen sind nicht erlaubt. Dar\u00fcber hinaus d\u00fcrfen Sie die Delfine oder Robben nicht ber\u00fchren, wenn Sie oder jemand in Ihrer Gruppe ansteckende Krankheiten hat. Kinder unter 90 cm K\u00f6rpergr\u00f6\u00dfe haben freien Eintritt und ben\u00f6tigen keinen Sitzplatz.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2216\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2216\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gibt es im Dolphins Bay Phuket Bestimmungen f\u00fcr Kinder?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2216\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2216\"><p><span style=\"color: #000000;\">Ja. Kinder unter 90 cm haben freien Eintritt, bekommen aber keinen Sitzplatz. F\u00fcr Kinder zwischen 90 und 130 cm gilt der Kindertarif. Das Schwimmen mit Delfinen ist f\u00fcr Kinder ab 6 Jahren gestattet.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2217\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2217\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie buche ich Tickets f\u00fcr Dolphins Bay Phuket?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2217\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2217\"><p><span style=\"color: #000000;\">Alle Buchungen m\u00fcssen mindestens einen Tag im Voraus vor 18:00 Uhr (thail\u00e4ndische Zeit) erfolgen. Sie k\u00f6nnen Tickets ganz einfach online \u00fcber unsere Website buchen. Die Ticketoptionen reichen von normalen Sitzpl\u00e4tzen bis hin zu VVIP-Sitzpl\u00e4tzen und sogar Delphinschwimmsitzungen.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2218\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2218\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie sind die Stornierungsbedingungen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2218\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2218\"><p><span style=\"color: #000000;\">Dolphins Bay Phuket verfolgt eine strikte Richtlinie, die keine R\u00fcckerstattungen und keine Stornierungen vorsieht. Bitte stellen Sie sicher, dass Sie mit dem richtigen Datum und Sitzplatzwunsch buchen.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2219\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2219\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gibt es Erm\u00e4\u00dfigungen oder Sonderangebote f\u00fcr Tickets?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2219\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2219\"><p><span style=\"color: #000000;\">Ja, es gibt oft Sonderangebote und Rabatte f\u00fcr Online-Buchungen. Behalten Sie unsere Website im Auge, um die neuesten Angebote f\u00fcr VVIP-, VIP-, Deluxe- und regul\u00e4re Tickets zu sehen.<\/span><\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-22110\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-22110\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Welche Aktivit\u00e4ten kann ich au\u00dfer den Shows genie\u00dfen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-22110\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-22110\"><p><span style=\"color: #000000;\">Zus\u00e4tzlich zu den Robben- und Delfinshows k\u00f6nnen Sie an Aktivit\u00e4ten wie Schwimmen mit Delfinen, Fotografieren mit Delfinen und Robben teilnehmen und am \u201eMagic Touch\u201c-Erlebnis teilnehmen, bei dem Sie die Delfine aus n\u00e4chster N\u00e4he erleben k\u00f6nnen.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What are the show timings at Dolphins Bay Phuket?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">Dolphins Bay Phuket offers three shows daily: 11:00 AM, 2:00 PM, and 5:00 PM, except on Mondays. Each show begins with a 15-minute seal show followed by a 25-minute dolphin show. The gates open 15 minutes before the scheduled show time.<\\\/span><\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Where is Dolphins Bay Phuket located?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">Dolphins Bay Phuket is located at 33\\\/50, Chalong, Mueang Phuket District, Phuket 83130, Thailand. You can easily find the location using <a style=\\\"color: #000000;\\\" href=\\\"https:\\\/\\\/maps.app.goo.gl\\\/iKaEd3g2Nr1B9YJD8\\\" target=\\\"_new\\\" rel=\\\"noopener\\\">Google Maps<\\\/a>.<\\\/span><\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What are the different seating options available?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">Dolphins Bay Phuket offers several seating categories:<\\\/span><\\\/p><ul><li><span style=\\\"color: #000000;\\\"><strong>VVIP<\\\/strong>: Row A<\\\/span><\\\/li><li><span style=\\\"color: #000000;\\\"><strong>VIP<\\\/strong>: Row B<\\\/span><\\\/li><li><span style=\\\"color: #000000;\\\"><strong>Deluxe<\\\/strong>: Rows C and D<\\\/span><\\\/li><li><span style=\\\"color: #000000;\\\"><strong>Regular<\\\/strong>: Rows E, F, and G<\\\/span><br \\\/><span style=\\\"color: #000000;\\\">Each ticket includes access to the seal and dolphin shows, with premium seating providing the best views.<\\\/span><\\\/li><\\\/ul>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Can I swim with the dolphins at Dolphins Bay Phuket?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">Yes! Swimming with dolphins is one of the unique activities offered. It is available for adults and children aged 6 years and older. Children aged 4 to 5 must be accompanied by a parent, with an additional charge.<\\\/span><\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What should I know before visiting Dolphins Bay Phuket?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">Please arrive 15 minutes before the show starts. Smoking is prohibited, and no pets or glass bottles are allowed. Additionally, if you or anyone in your group has contagious diseases, you will not be allowed to touch the dolphins or seals. Children under 90 cm in height can enter for free without a seat.<\\\/span><\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Is there a child policy at Dolphins Bay Phuket?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">Yes. Children under 90 cm are free but will not be provided a seat. Children between 90 \\u2013 130 cm are charged as children. Swimming with dolphins is permitted for children 6 years and older.<\\\/span><\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"How do I book tickets for Dolphins Bay Phuket?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">All bookings should be made at least one day in advance before 6:00 PM (Thailand time). You can easily book tickets online through our website. Ticket options range from regular seats to VVIP seats and even dolphin swimming sessions.<\\\/span><\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What is the cancellation policy?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">Dolphins Bay Phuket follows a strict no-refund and no-cancellation policy. Please ensure that you book with the correct date and seating preference.<\\\/span><\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Are there discounts or special deals on tickets?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">Yes, there are often special deals and discounts for online bookings. Keep an eye on our website for the latest offers on VVIP, VIP, Deluxe, and Regular tickets.<\\\/span><\\\/p><p>\\u00a0<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What activities can I enjoy besides the shows?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p><span style=\\\"color: #000000;\\\">In addition to the seal and dolphin shows, you can enjoy activities like swimming with dolphins, taking photos with the dolphins and seals, and participating in the \\u201cMagic Touch\\u201d experience where you can interact with the dolphins up close.<\\\/span><\\\/p>\"\n            }\n        }\n    ]\n}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Delfinshow Phuket \u2013 Dolphins Bay Phuket Tickets 4,7 (4,3 Tsd. Bewertungen) Triplyn Holidays ist eine vertrauensw\u00fcrdige Marke, die kuratierte Erlebnisse anbietet, mit denen Sie die Delfinshow Phuket erkunden k\u00f6nnen. Buchen Sie vertrauensvoll und genie\u00dfen Sie ein nahtloses Abenteuer, das f\u00fcr ein unvergessliches Erlebnis bei einer der Topattraktionen Thailands konzipiert wurde. Triplyn Holidays bietet ein unvergessliches Delfinshow-Erlebnis in Phuket. [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Book Dolphin Show Phuket Tickets - Visit Dolphins Bay Phuket<\/title>\n<meta name=\"description\" content=\"Explore Dolphins Bay Phuket! Book Dolphin Show Tickets Now For A Day Of Excitement, Family Fun, And Thrilling Performances. Secure Your Seats\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Book Dolphin Show Phuket Tickets - Visit Dolphins Bay Phuket\" \/>\n<meta property=\"og:description\" content=\"Explore Dolphins Bay Phuket! Book Dolphin Show Tickets Now For A Day Of Excitement, Family Fun, And Thrilling Performances. Secure Your Seats\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ancientcitybangkok.com\/de\" \/>\n<meta property=\"og:site_name\" content=\"Ancient City Bangkok\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-04T19:54:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"87\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ancientcitybangkok.com\/\",\"url\":\"https:\/\/ancientcitybangkok.com\/\",\"name\":\"Book Dolphin Show Phuket Tickets - Visit Dolphins Bay Phuket\",\"isPartOf\":{\"@id\":\"https:\/\/ancientcitybangkok.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ancientcitybangkok.com\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ancientcitybangkok.com\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.avif\",\"datePublished\":\"2024-08-28T06:26:50+00:00\",\"dateModified\":\"2025-05-04T19:54:04+00:00\",\"description\":\"Explore Dolphins Bay Phuket! Book Dolphin Show Tickets Now For A Day Of Excitement, Family Fun, And Thrilling Performances. Secure Your Seats\",\"breadcrumb\":{\"@id\":\"https:\/\/ancientcitybangkok.com\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ancientcitybangkok.com\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/ancientcitybangkok.com\/#primaryimage\",\"url\":\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.avif\",\"contentUrl\":\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.avif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ancientcitybangkok.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ancientcitybangkok.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ancientcitybangkok.com\/#website\",\"url\":\"https:\/\/ancientcitybangkok.com\/\",\"name\":\"Dolphin Show Phuket\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ancientcitybangkok.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ancientcitybangkok.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ancientcitybangkok.com\/#organization\",\"name\":\"Dolphin Show Phuket\",\"url\":\"https:\/\/ancientcitybangkok.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/ancientcitybangkok.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dophin-Show-Phuket.png\",\"contentUrl\":\"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dophin-Show-Phuket.png\",\"width\":350,\"height\":100,\"caption\":\"Dolphin Show Phuket\"},\"image\":{\"@id\":\"https:\/\/ancientcitybangkok.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Book Dolphin Show Phuket Tickets - Visit Dolphins Bay Phuket","description":"Explore Dolphins Bay Phuket! Book Dolphin Show Tickets Now For A Day Of Excitement, Family Fun, And Thrilling Performances. Secure Your Seats","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Book Dolphin Show Phuket Tickets - Visit Dolphins Bay Phuket","og_description":"Explore Dolphins Bay Phuket! Book Dolphin Show Tickets Now For A Day Of Excitement, Family Fun, And Thrilling Performances. Secure Your Seats","og_url":"https:\/\/ancientcitybangkok.com\/de","og_site_name":"Ancient City Bangkok","article_modified_time":"2025-05-04T19:54:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"87\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ancientcitybangkok.com\/","url":"https:\/\/ancientcitybangkok.com\/","name":"Book Dolphin Show Phuket Tickets - Visit Dolphins Bay Phuket","isPartOf":{"@id":"https:\/\/ancientcitybangkok.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ancientcitybangkok.com\/#primaryimage"},"image":{"@id":"https:\/\/ancientcitybangkok.com\/#primaryimage"},"thumbnailUrl":"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.avif","datePublished":"2024-08-28T06:26:50+00:00","dateModified":"2025-05-04T19:54:04+00:00","description":"Explore Dolphins Bay Phuket! Book Dolphin Show Tickets Now For A Day Of Excitement, Family Fun, And Thrilling Performances. Secure Your Seats","breadcrumb":{"@id":"https:\/\/ancientcitybangkok.com\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ancientcitybangkok.com\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ancientcitybangkok.com\/#primaryimage","url":"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.avif","contentUrl":"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/10\/Dolphin-Show-Phuket.avif"},{"@type":"BreadcrumbList","@id":"https:\/\/ancientcitybangkok.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ancientcitybangkok.com\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/ancientcitybangkok.com\/#website","url":"https:\/\/ancientcitybangkok.com\/","name":"Dolphin Show Phuket","description":"","publisher":{"@id":"https:\/\/ancientcitybangkok.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ancientcitybangkok.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ancientcitybangkok.com\/#organization","name":"Dolphin Show Phuket","url":"https:\/\/ancientcitybangkok.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ancientcitybangkok.com\/#\/schema\/logo\/image\/","url":"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dophin-Show-Phuket.png","contentUrl":"https:\/\/ancientcitybangkok.com\/wp-content\/uploads\/2024\/08\/Dophin-Show-Phuket.png","width":350,"height":100,"caption":"Dolphin Show Phuket"},"image":{"@id":"https:\/\/ancientcitybangkok.com\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ancientcitybangkok.com\/de\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ancientcitybangkok.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ancientcitybangkok.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ancientcitybangkok.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancientcitybangkok.com\/de\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":621,"href":"https:\/\/ancientcitybangkok.com\/de\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":3090,"href":"https:\/\/ancientcitybangkok.com\/de\/wp-json\/wp\/v2\/pages\/10\/revisions\/3090"}],"wp:attachment":[{"href":"https:\/\/ancientcitybangkok.com\/de\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}